{"id":14691,"date":"2015-04-23T16:20:22","date_gmt":"2015-04-23T14:20:22","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/?p=14691"},"modified":"2015-05-04T15:46:47","modified_gmt":"2015-05-04T13:46:47","slug":"concierto-inaugural-semana-de-la-lectura-de-alqueria","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2015\/04\/23\/concierto-inaugural-semana-de-la-lectura-de-alqueria\/","title":{"rendered":"Concierto Inaugural Semana de la lectura de Alquer\u00eda"},"content":{"rendered":"<p><strong><em><span style=\"color: #333399\">A continuaci\u00f3n os dejo una muestra del Concierto que abri\u00f3 nuestra Semana de la lectura 2015. Espero que os guste, a vuestros peque\u00f1os seguro que les encantar\u00e1 recordarlo&#8230;&#8230;<\/span><\/em><\/strong><\/p>\n<p><a href=\"https:\/\/vimeo.com\/125681827\">https:\/\/vimeo.com\/125681827<\/a><\/p>\n<p><strong><em><span style=\"color: #333399\">Esta actividad fue posible gracias a la inestimable colaboraci\u00f3n de Jaume Esteve y Elena Iruela, \u00a1muchas gracias a los dos!<\/span><\/em><\/strong><\/p>\n<p style=\"text-align: right\"><strong><em><span style=\"color: #333399\">Loli G\u00e1lvez<\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n os dejo una muestra del Concierto que abri\u00f3 nuestra Semana de la lectura 2015. Espero que os guste, a vuestros peque\u00f1os seguro que les encantar\u00e1 recordarlo&#8230;&#8230; Esta actividad fue posible gracias a la inestimable colaboraci\u00f3n de Jaume Esteve y Elena Iruela, \u00a1muchas gracias a los dos! Loli G\u00e1lvez<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,8],"tags":[268],"class_list":["post-14691","post","type-post","status-publish","format-standard","hentry","category-clase-naranja","category-diario","tag-semana-lectura-infantil-2015"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lG08-3OX","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/14691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=14691"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/14691\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=14691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=14691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=14691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}