{"id":24290,"date":"2017-02-07T16:30:31","date_gmt":"2017-02-07T15:30:31","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/?p=24290"},"modified":"2017-02-07T14:26:32","modified_gmt":"2017-02-07T13:26:32","slug":"taller-creativo-pintamos-con-pincel-2","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/","title":{"rendered":"TALLER CREATIVO: Pintamos con pincel"},"content":{"rendered":"<p>Comenzamos con los preparativos para el <span style=\"color: #008000\">Carnaval<\/span>. Como el disfraz lo vamos a elaborar nosotros\/as, lo iremos haciendo poco a poco para disfrutar el proceso.<\/p>\n<p>Hoy tenemos un <span style=\"color: #008000\">taller creativo<\/span> donde le damos color rosa a lo que va a ser la nariz de cerdit@. Utilizamos cart\u00f3n de huevos para recortarlas y con <span style=\"color: #008000\">pinceles<\/span> les van dando color. Ha sido algo dif\u00edcil ya que la superficie que hab\u00eda que cubrir con pintura era algo peque\u00f1a y no quer\u00edan mancharse los dedos, pero lo han conseguido. Cuando est\u00e9n secas le pondremos una goma y nos las probaremos a ver como quedan.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:9,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriaamarillanaranja\\\/2017\\\/02\\\/07\\\/taller-creativo-pintamos-con-pincel-2\\\/&quot;,&quot;likes_blog_id&quot;:64271688}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 238px;\" data-original-width=\"474\" data-original-height=\"238\" > <div class=\"gallery-group images-1\" style=\"width: 316px; height: 238px;\" data-original-width=\"316\" data-original-height=\"238\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7667\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"312\"> <meta itemprop=\"height\" content=\"234\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24291\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7667\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667.jpg?w=312&#038;h=234&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7667.jpg 768w\" width=\"312\" height=\"234\" loading=\"lazy\" data-original-width=\"312\" data-original-height=\"234\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7667\" alt=\"IMG_7667\" style=\"width: 312px; height: 234px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 158px; height: 238px;\" data-original-width=\"158\" data-original-height=\"238\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7668\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"115\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24292\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7668\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668.jpg?w=154&#038;h=115&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7668.jpg 768w\" width=\"154\" height=\"115\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"115\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7668\" alt=\"IMG_7668\" style=\"width: 154px; height: 115px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7669\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"115\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24293\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7669\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669.jpg?w=154&#038;h=115&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7669.jpg 768w\" width=\"154\" height=\"115\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"115\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7669\" alt=\"IMG_7669\" style=\"width: 154px; height: 115px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 474px; height: 357px;\" data-original-width=\"474\" data-original-height=\"357\" > <div class=\"gallery-group images-1\" style=\"width: 474px; height: 357px;\" data-original-width=\"474\" data-original-height=\"357\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7670\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"470\"> <meta itemprop=\"height\" content=\"353\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24294\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7670\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670.jpg?w=470&#038;h=353&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7670.jpg 768w\" width=\"470\" height=\"353\" loading=\"lazy\" data-original-width=\"470\" data-original-height=\"353\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7670\" alt=\"IMG_7670\" style=\"width: 470px; height: 353px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>En la<span style=\"color: #008000\"> Asamblea con Lindley<\/span>, pasamos lista y elegimos a la s\u00faper de hoy que ha sido <span style=\"color: #008000\">ADRIANA<\/span> que reparte la fruta. Dedican este momento tan tranquilo para cantar las canciones que se saben sobre \u00abEl tiempo y los animales\u00bb.<\/p>\n<p>Aprovechando el buen tiempo nos bajamos al <span style=\"color: #008000\">Parque<\/span> y disfrutamos del arenero, de las motos, las carretillas&#8230;. La compa\u00f1\u00eda de l@s mayores de primaria les gusta mucho y es un momento muy especial para tod@s.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:9,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriaamarillanaranja\\\/2017\\\/02\\\/07\\\/taller-creativo-pintamos-con-pincel-2\\\/&quot;,&quot;likes_blog_id&quot;:64271688}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 238px;\" data-original-width=\"474\" data-original-height=\"238\" > <div class=\"gallery-group images-1\" style=\"width: 316px; height: 238px;\" data-original-width=\"316\" data-original-height=\"238\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7677\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"312\"> <meta itemprop=\"height\" content=\"234\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24301\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7677\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677.jpg?w=312&#038;h=234&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7677.jpg 768w\" width=\"312\" height=\"234\" loading=\"lazy\" data-original-width=\"312\" data-original-height=\"234\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7677\" alt=\"IMG_7677\" style=\"width: 312px; height: 234px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 158px; height: 238px;\" data-original-width=\"158\" data-original-height=\"238\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7676\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"115\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24300\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7676\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676.jpg?w=154&#038;h=115&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7676.jpg 768w\" width=\"154\" height=\"115\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"115\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7676\" alt=\"IMG_7676\" style=\"width: 154px; height: 115px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7675\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"115\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24299\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7675\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675.jpg?w=154&#038;h=115&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7675.jpg 768w\" width=\"154\" height=\"115\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"115\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7675\" alt=\"IMG_7675\" style=\"width: 154px; height: 115px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 474px; height: 120px;\" data-original-width=\"474\" data-original-height=\"120\" > <div class=\"gallery-group images-1\" style=\"width: 158px; height: 120px;\" data-original-width=\"158\" data-original-height=\"120\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7674\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"116\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24298\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7674\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674.jpg?w=154&#038;h=116&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7674.jpg 768w\" width=\"154\" height=\"116\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"116\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7674\" alt=\"IMG_7674\" style=\"width: 154px; height: 116px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 158px; height: 120px;\" data-original-width=\"158\" data-original-height=\"120\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7673\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"116\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24297\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7673\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673.jpg?w=154&#038;h=116&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7673.jpg 768w\" width=\"154\" height=\"116\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"116\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7673\" alt=\"IMG_7673\" style=\"width: 154px; height: 116px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 158px; height: 120px;\" data-original-width=\"158\" data-original-height=\"120\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/img_7671\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"154\"> <meta itemprop=\"height\" content=\"116\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24295\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7671\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671.jpg?w=154&#038;h=116&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7671.jpg 768w\" width=\"154\" height=\"116\" loading=\"lazy\" data-original-width=\"154\" data-original-height=\"116\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7671\" alt=\"IMG_7671\" style=\"width: 154px; height: 116px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>Nos faltan algunas camisetas para el disfraz, las esperamos esta semana.<\/p>\n<p><span style=\"color: #008000\">Gracias<\/span><\/p>\n<p>Carmen Jim\u00e9nez<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comenzamos con los preparativos para el Carnaval. Como el disfraz lo vamos a elaborar nosotros\/as, lo iremos haciendo poco a poco para disfrutar el proceso. Hoy tenemos un taller creativo donde le damos color rosa a lo que va a ser la nariz de cerdit@. Utilizamos cart\u00f3n de huevos para recortarlas y con pinceles les &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/07\/taller-creativo-pintamos-con-pincel-2\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">TALLER CREATIVO: Pintamos con pincel<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,9,18],"tags":[],"class_list":["post-24290","post","type-post","status-publish","format-standard","hentry","category-clase-amarilla","category-diario-clase-amarilla","category-talleres"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lG08-6jM","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/24290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=24290"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/24290\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=24290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=24290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=24290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}