{"id":24550,"date":"2017-02-17T20:47:09","date_gmt":"2017-02-17T19:47:09","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/?p=24550"},"modified":"2017-02-17T20:47:09","modified_gmt":"2017-02-17T19:47:09","slug":"logica-matematica-9","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/","title":{"rendered":"L\u00d3GICA-MATEM\u00c1TICA"},"content":{"rendered":"<p>En la \u00a0Asamblea de inicio pasamos lista como cada d\u00eda y elegimos al s\u00faper que ha sido <span style=\"color: #ff00ff\">Giacomo<\/span>. Seguidamente eligen a qu\u00e9 quieren jugar y por mayor\u00eda ha salido <span style=\"color: #ff00ff\">los beb\u00e9s<\/span> con los carritos y las <span style=\"color: #ff00ff\">herramientas.\u00a0<span style=\"color: #333333\">Mientras ellos est\u00e1n jugando comenzamos a pintar las camisetas para nuestro disfraz, la semana que viene las <img decoding=\"async\" data-attachment-id=\"24555\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7792\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7792.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7792\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7792-1024x768.jpg\" class=\"alignright size-thumbnail wp-image-24555\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7792-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>expondremos fuera.<\/span><\/span><\/p>\n<p>Hoy les propongo un juego de <span style=\"color: #800080\">estimaci\u00f3n de cantidades<\/span> a trav\u00e9s de unas l\u00e1minas con c\u00edrculos de diferentes tama\u00f1os y colocaci\u00f3n en el espacio; trabajamos las cantidades 1, 2 y 3.<\/p>\n<p>La actividad consiste en ense\u00f1arles la l\u00e1mina durante un segundo y ellos responder lo m\u00e1s r\u00e1pido posible. Ha sido muy curioso como sacaban los deditos para indicar la cantidad antes de verbalizarlo. Lo han hecho muy bien. Despu\u00e9s practicamos de manera manipulativa relacionando la cantidad de c\u00edrculos con las piezas que ten\u00edan que poner.<\/p>\n<div class=\"tiled-gallery type-circle tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:9,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriaamarillanaranja\\\/2017\\\/02\\\/17\\\/logica-matematica-9\\\/&quot;,&quot;likes_blog_id&quot;:64271688}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7783\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24551\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7783.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7783\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7783-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7783-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7783.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7783\" alt=\"IMG_7783\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7788\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24552\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7788.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7788\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7788-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7788-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7788.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7788\" alt=\"IMG_7788\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7789\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24553\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7789.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7789\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7789-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7789-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7789.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7789\" alt=\"IMG_7789\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7790\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"24554\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7790.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7790\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7790-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7790-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7790.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_7790\" alt=\"IMG_7790\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <\/div> <\/div>\n<p>Y para terminar el viernes nos reunimos <span style=\"color: #ff00ff\">el ciclo 0-3 a\u00f1os<\/span> y montamos las letras en el <span style=\"color: #ff00ff\">cartel para la fiesta de Carnaval<\/span>, \u00a0pod\u00e9is ver lo bonito que ha quedado en el hall de la clase.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"24558\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/img_7799\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_7799\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799-1024x768.jpg\" class=\"aligncenter size-medium wp-image-24558\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2017\/02\/IMG_7799.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Y con todo esto nos despedimos hasta el lunes, buen fin de semana.<\/p>\n<p>Carmen Jim\u00e9nez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la \u00a0Asamblea de inicio pasamos lista como cada d\u00eda y elegimos al s\u00faper que ha sido Giacomo. Seguidamente eligen a qu\u00e9 quieren jugar y por mayor\u00eda ha salido los beb\u00e9s con los carritos y las herramientas.\u00a0Mientras ellos est\u00e1n jugando comenzamos a pintar las camisetas para nuestro disfraz, la semana que viene las expondremos fuera. &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2017\/02\/17\/logica-matematica-9\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">L\u00d3GICA-MATEM\u00c1TICA<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,9],"tags":[],"class_list":["post-24550","post","type-post","status-publish","format-standard","hentry","category-clase-amarilla","category-diario-clase-amarilla"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lG08-6nY","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/24550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=24550"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/24550\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=24550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=24550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=24550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}