{"id":52876,"date":"2021-11-26T17:20:54","date_gmt":"2021-11-26T16:20:54","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/?p=52876"},"modified":"2021-11-27T15:49:26","modified_gmt":"2021-11-27T14:49:26","slug":"nos-divertimos-en-el-patio","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/","title":{"rendered":"Nos divertimos en el patio."},"content":{"rendered":"<p>Buenas tardes, familia,<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"52885\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/65df5ea0e2673ce3eb08c749ffeec090\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090.jpg\" data-orig-size=\"2500,1818\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"65df5ea0e2673ce3eb08c749ffeec090\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-1024x745.jpg\" class=\"alignleft wp-image-52885\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-300x218.jpg\" alt=\"\" width=\"238\" height=\"173\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-300x218.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-1024x745.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-768x558.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-1536x1117.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/65df5ea0e2673ce3eb08c749ffeec090-2048x1489.jpg 2048w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>ya es viernes y el cuerpo lo sabe. Hoy ha sido un gran d\u00eda en la clase Naranja. Como cada viernes, vienen nuestros especialistas al aula.<\/p>\n<p>Hoy en m\u00fasica hemos cantado varios villancicos como \u00ablos peces en el r\u00edo\u00bb o \u00abcampana sobre campana\u00bb y los hemos acompa\u00f1ado con los vasos de pl\u00e1stico siguiendo el ritmo.<\/p>\n<p>Luego ha venido Tatiana a darnos la clase de E. F\u00edsica. Hemos calentado en clase haciendo juegos tradicionales&#8230; <em>\u00bfadivin\u00e1is cu\u00e1les?<\/em> Despu\u00e9s hemos bajado a la pista a jugar con los aros y pelotas.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:9,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriaamarillanaranja\\\/2021\\\/11\\\/26\\\/nos-divertimos-en-el-patio\\\/&quot;,&quot;likes_blog_id&quot;:64271688}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 179px;\" data-original-width=\"474\" data-original-height=\"179\" > <div class=\"gallery-group images-1\" style=\"width: 237px; height: 179px;\" data-original-width=\"237\" data-original-height=\"179\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/whatsapp-image-2021-11-26-at-14-19-24\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"175\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"52878\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-11-26 at 14.19.24\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24.jpeg?w=233&#038;h=175&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24.jpeg 1600w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-300x225.jpeg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-1024x768.jpeg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-768x576.jpeg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.24-1536x1152.jpeg 1536w\" width=\"233\" height=\"175\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"175\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2021-11-26 at 14.19.24\" alt=\"WhatsApp Image 2021-11-26 at 14.19.24\" style=\"width: 233px; height: 175px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 237px; height: 179px;\" data-original-width=\"237\" data-original-height=\"179\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/whatsapp-image-2021-11-26-at-14-19-241\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"175\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"52877\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-11-26 at 14.19.24(1)\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241.jpeg?w=233&#038;h=175&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241.jpeg 1600w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-300x225.jpeg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-1024x768.jpeg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-768x576.jpeg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/WhatsApp-Image-2021-11-26-at-14.19.241-1536x1152.jpeg 1536w\" width=\"233\" height=\"175\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"175\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2021-11-26 at 14.19.24(1)\" alt=\"WhatsApp Image 2021-11-26 at 14.19.24(1)\" style=\"width: 233px; height: 175px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>Los viernes nos toca laberinto. Hemos disfrutado del solecito que ha hecho esta ma\u00f1ana, jugando con las hojas de oto\u00f1o que ya est\u00e1n en el suelo. Hemos disfrutado hoy de una rica comida de viernes.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-52876-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.252.jpeg&quot;,&quot;id&quot;:&quot;52879&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.25(2)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.251.jpeg&quot;,&quot;id&quot;:&quot;52880&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.25(1)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.25.jpeg&quot;,&quot;id&quot;:&quot;52881&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.25&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.244.jpeg&quot;,&quot;id&quot;:&quot;52882&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.24(4)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.243.jpeg&quot;,&quot;id&quot;:&quot;52883&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.24(3)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2021\\\/11\\\/WhatsApp-Image-2021-11-26-at-14.19.242.jpeg&quot;,&quot;id&quot;:&quot;52884&quot;,&quot;title&quot;:&quot;WhatsApp Image 2021-11-26 at 14.19.24(2)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p><img decoding=\"async\" data-attachment-id=\"52886\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/estamos_aqui_portada\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/Estamos_Aqui_portada.jpg\" data-orig-size=\"469,591\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Estamos_Aqui_portada\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/Estamos_Aqui_portada.jpg\" class=\"size-medium wp-image-52886 alignright\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/Estamos_Aqui_portada-238x300.jpg\" alt=\"\" width=\"238\" height=\"300\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/Estamos_Aqui_portada-238x300.jpg 238w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2021\/11\/Estamos_Aqui_portada.jpg 469w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>Por la tarde lo pasamos genial recogiendo las hojas, cuidamos del patio y encima nos divertimos. Leemos un libro que nos cuenta muchas cosas, sobre todo que planeta Tierra solo hay uno y hay que cuidarlo&#8230; <em>\u00bfc\u00f3mo crees que podemos contribuir a cuidarlo?<\/em> Nosotros hemos propuesto no dejar el grifo abierto, comernos todo lo del plato y apagar las luces si hay sol.<\/p>\n<p>Esto ha sido por el d\u00eda de hoy, familia.<\/p>\n<p>Esperamos que pas\u00e9is un buen fin de semana y pod\u00e1is descansar.<\/p>\n<p>Un abrazo,<\/p>\n<p>Mar\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas tardes, familia, ya es viernes y el cuerpo lo sabe. Hoy ha sido un gran d\u00eda en la clase Naranja. Como cada viernes, vienen nuestros especialistas al aula. Hoy en m\u00fasica hemos cantado varios villancicos como \u00ablos peces en el r\u00edo\u00bb o \u00abcampana sobre campana\u00bb y los hemos acompa\u00f1ado con los vasos de pl\u00e1stico &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2021\/11\/26\/nos-divertimos-en-el-patio\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Nos divertimos en el patio.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,10],"tags":[610,176],"class_list":["post-52876","post","type-post","status-publish","format-standard","hentry","category-clase-naranja","category-especialistas","tag-medioambiente","tag-tardes-cooperativas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lG08-dKQ","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/52876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=52876"}],"version-history":[{"count":3,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/52876\/revisions"}],"predecessor-version":[{"id":52894,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/52876\/revisions\/52894"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=52876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=52876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=52876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}