{"id":5889,"date":"2013-05-28T14:39:07","date_gmt":"2013-05-28T12:39:07","guid":{"rendered":"http:\/\/alqueriaamarillanaranja.wordpress.com\/?p=5889"},"modified":"2014-02-24T12:53:07","modified_gmt":"2014-02-24T12:53:07","slug":"cuentos-audiovisuales","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2013\/05\/28\/cuentos-audiovisuales\/","title":{"rendered":"CUENTOS AUDIOVISUALES"},"content":{"rendered":"<p style=\"text-align:justify\">Pasamos la ma\u00f1ana muy tranquilos jugando a los m\u00e9dicos y a los animales.<\/p>\n<p style=\"text-align:justify\">Hacen sus grupillos y cada vez el juego se desarrolla de forma m\u00e1s creativa, imitando acciones de los adultos y en algunos\/as\u00a0 aparece un<span style=\"color:#800000\"> juego simb\u00f3lico.<\/span><\/p>\n<p style=\"text-align:justify\">Despu\u00e9s de recoger, que tardamos un rato, porque hay quien se \u00abescabulle\u00bb&#8230;.preparamos el ordenador y tenemos una sesi\u00f3n de cuentos audiovisuales: \u00abElmer el elefante de colores\u00bb en espa\u00f1ol y en ingl\u00e9s. Han estado super atentos\/as a la hist\u00f3ria y se han quedado con ganas de m\u00e1s&#8230;.<\/p>\n<p style=\"text-align:justify\">En la asamblea reparte como s\u00faper<span style=\"color:#800000\"> JUAN.<\/span><\/p>\n<p style=\"text-align:justify\">\u00a0<a href=\"http:\/\/alqueriaamarillanaranja.files.wordpress.com\/2013\/05\/sshot-31.png\"><img decoding=\"async\" data-attachment-id=\"5894\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/sshot-31-2\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/05\/sshot-31.png\" data-orig-size=\"433,511\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"sshot-3[1]\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/05\/sshot-31.png\" class=\"aligncenter size-medium wp-image-5894\" alt=\"sshot-3[1]\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2013\/05\/sshot-311.png\" width=\"254\" height=\"300\" \/><\/a><\/p>\n<h5><span style=\"color:#ff0000\">Recordar que el pr\u00f3ximo Miercoles 5 de Junio es nuestra salida<\/span><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Pasamos la ma\u00f1ana muy tranquilos jugando a los m\u00e9dicos y a los animales. Hacen sus grupillos y cada vez el juego se desarrolla de forma m\u00e1s creativa, imitando acciones de los adultos y en algunos\/as\u00a0 aparece un juego simb\u00f3lico. Despu\u00e9s de recoger, que tardamos un rato, porque hay quien se \u00abescabulle\u00bb&#8230;.preparamos el ordenador y tenemos &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2013\/05\/28\/cuentos-audiovisuales\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">CUENTOS AUDIOVISUALES<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[22,6],"tags":[285,90],"class_list":["post-5889","post","type-post","status-publish","format-standard","hentry","category-cancionero","category-clase-amarilla","tag-alfabetizacion","tag-medios-audiovisuales"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lG08-1wZ","jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/5889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=5889"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/5889\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=5889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=5889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=5889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}