{"id":7587,"date":"2013-12-11T15:38:52","date_gmt":"2013-12-11T14:38:52","guid":{"rendered":"http:\/\/alqueriaamarillanaranja.wordpress.com\/?p=7587"},"modified":"2014-02-24T12:46:02","modified_gmt":"2014-02-24T12:46:02","slug":"7587","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2013\/12\/11\/7587\/","title":{"rendered":"Un d\u00eda lleno de actividad"},"content":{"rendered":"<p><em><span style=\"color:#993366\"><a href=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2013\/12\/images1.jpg\"><img decoding=\"async\" data-attachment-id=\"7589\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/images-31\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/12\/images.jpg\" data-orig-size=\"273,185\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"images\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/12\/images.jpg\" class=\"alignleft size-full wp-image-7589\" alt=\"images\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2013\/12\/images1.jpg\" width=\"273\" height=\"185\" \/><\/a>Esta ma\u00f1ana ha primera hora en nuestra sesi\u00f3n psicomotriz, jugamos con los t\u00faneles y construimos \u00ablas casas de los tres cerditos\u00bb con las telas grandes en las mesas de la clase. Este juego les encanta.<\/span><\/em><\/p>\n<p><em><span style=\"color:#993366\">Despu\u00e9s hemos tenido Juego Heur\u00edstico con los siguientes materiales: anillas, cucharas de madera, tapaderas y latas. Hoy la propuesta m\u00e1s secundada a sido la percusi\u00f3n, usando las cucharas de madera han ido golpeando los diferentes materiales hasta que han descubierto que el efecto producido por las latas pod\u00eda asemejarse al de un tambor. \u00a1Os pod\u00e9is imaginar el concierto&#8230;.!<\/span><\/em><\/p>\n<p><em><span style=\"color:#993366\">En ingl\u00e9s hemos acabado nuestro \u00absnowman\u00bb; hoy acabamos la <a href=\"http:\/\/alqueriaamarillanaranja.files.wordpress.com\/2013\/12\/10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos1.jpg\"><img decoding=\"async\" data-attachment-id=\"7588\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos1\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/12\/10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos1.jpg\" data-orig-size=\"400,400\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos[1]\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-content\/uploads\/sites\/9\/2013\/12\/10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos1.jpg\" class=\"alignright  wp-image-7588\" alt=\"10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos[1]\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/9\/2013\/12\/10988104-invierno-muneco-de-nieve-de-dibujos-animados-dibujos-animados-ilustracion-vectorial-para-los-ninos11.jpg\" width=\"240\" height=\"240\" \/><\/a>composici\u00f3n pegando los ojos, la nariz y la bufanda. Han quedado gracios\u00edsimos, pod\u00e9is verlos expuestos.<\/span><\/em><\/p>\n<p><em><span style=\"color:#993366\">Y en el patio, disfrutamos de una ma\u00f1ana casi, casi primaveral. Es un placer el juego en este espacio.<\/span><\/em><\/p>\n<p><em><span style=\"color:#993366\">Esta tarde despide el grupo Alba porque yo tengo reuni\u00f3n. Ma\u00f1ana os veo.<\/span><\/em><\/p>\n<p style=\"text-align:right\"><em><span style=\"color:#993366\">Loli G\u00e1lvez<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana ha primera hora en nuestra sesi\u00f3n psicomotriz, jugamos con los t\u00faneles y construimos \u00ablas casas de los tres cerditos\u00bb con las telas grandes en las mesas de la clase. Este juego les encanta. Despu\u00e9s hemos tenido Juego Heur\u00edstico con los siguientes materiales: anillas, cucharas de madera, tapaderas y latas. Hoy la propuesta m\u00e1s &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/2013\/12\/11\/7587\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Un d\u00eda lleno de actividad<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,15],"tags":[73,288],"class_list":["post-7587","post","type-post","status-publish","format-standard","hentry","category-clase-amarilla","category-juego-heuristico","tag-ingles","tag-juego-heuristico"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s4lG08-7587","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/7587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/comments?post=7587"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/posts\/7587\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/media?parent=7587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/categories?post=7587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaamarillanaranja\/wp-json\/wp\/v2\/tags?post=7587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}