{"id":439,"date":"2015-11-27T10:03:05","date_gmt":"2015-11-27T09:03:05","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/?p=439"},"modified":"2015-11-27T10:03:05","modified_gmt":"2015-11-27T09:03:05","slug":"inauguracion-talleres-de-instrumento","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/2015\/11\/27\/inauguracion-talleres-de-instrumento\/","title":{"rendered":"Inauguraci\u00f3n Talleres de Instrumento"},"content":{"rendered":"<p>El pasado mes de Octubre inauguramos el comienzo de los talleres de instrumento con una peque\u00f1a jam sesion con la colaboraci\u00f3n de Jaume Esteve. Fue un excitante momento que pill\u00f3 por sorpresa a tod@s y que disfrutamos much\u00edsimo, ya que la bater\u00eda no es un instrumento al uso que estemos acostumbrados a ver y escuchar en el patio de un colegio. Os dejo video de una de las canciones que interpretamos de Bon Jovi.<br \/>\nUn saludo.<br \/>\nElena<\/p>\n<p>https:\/\/vimeo.com\/145635212<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mes de Octubre inauguramos el comienzo de los talleres de instrumento con una peque\u00f1a jam sesion con la colaboraci\u00f3n de Jaume Esteve. Fue un excitante momento que pill\u00f3 por sorpresa a tod@s y que disfrutamos much\u00edsimo, ya que la bater\u00eda no es un instrumento al uso que estemos acostumbrados a ver y escuchar &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/2015\/11\/27\/inauguracion-talleres-de-instrumento\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Inauguraci\u00f3n Talleres de Instrumento<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,3,4,5,6,7,8],"tags":[],"class_list":["post-439","post","type-post","status-publish","format-standard","hentry","category-1o-epo","category-2o-epo","category-3o-epo","category-4o-epo","category-5o-epo","category-6o-epo","category-infantil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4l36P-75","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/posts\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriamusica\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}