{"id":37608,"date":"2024-05-19T20:24:33","date_gmt":"2024-05-19T18:24:33","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/?p=37608"},"modified":"2024-05-19T20:24:33","modified_gmt":"2024-05-19T18:24:33","slug":"la-prehistoria-minerales","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/","title":{"rendered":"La prehistoria, minerales."},"content":{"rendered":"<h5><strong>La Prehistoria<\/strong><\/h5>\n<p>Seguimos inmersos en el estudio de la prehistoria, sabemos que no hay nada escrito que nos pueda confirmar c\u00f3mo era la vida humana\u00a0 en esa etapa pero somos conocedores\u00a0 que\u00a0 la arqueolog\u00eda, junto a otras ciencias\u00a0 como la geolog\u00eda, la paleontolog\u00eda, la qu\u00edmica o la f\u00edsica, que nos permiten obtener informaci\u00f3n del pasado de los humanos, partiendo de los restos materiales extra\u00eddos de los yacimientos arqueol\u00f3gicos, cuevas encontradas con arte rupestre que representaban escenas , se\u00a0 ha realizado un gran trabajo de investigaci\u00f3n y transmisi\u00f3n\u00a0 sobre el tema que\u00a0 nos permite conocer como era la vida en las distintas etapas de la prehistoria.<\/p>\n<p>Los minerales han sido muy importantes a lo largo de la vida en la tierra y despiertan un inter\u00e9s especial en\u00a0 las conferencias del grupo de primero.<\/p>\n<h5><span style=\"color: #0000ff\"><strong>Rocas y minerales por Adam\u00a0<\/strong><\/span><\/h5>\n<p>Adam nos ha presentado su informaci\u00f3n a trav\u00e9s de la pantalla para ayudarse con las im\u00e1genes y el texto ya que su nivel de idioma espa\u00f1ol est\u00e1 en proceso de dominio. A\u00fan as\u00ed ha realizado un gran esfuerzo de transmisi\u00f3n de la informaci\u00f3n prepara para compartir con sus compa\u00f1eros, todo un reto para \u00e9l.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37611\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/screenshot_2024-05-12-14-23-26-125_com-microsoft-office-officehubrow2\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2.jpg\" data-orig-size=\"1076,1218\" data-comments-opened=\"1\" data-image-title=\"Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow~2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2-905x1024.jpg\" class=\"alignnone size-large wp-image-37611\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2-905x1024.jpg\" alt=\"\" width=\"474\" height=\"536\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2-905x1024.jpg 905w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2-265x300.jpg 265w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2-768x869.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-26-125_com.microsoft.office.officehubrow2.jpg 1076w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Nos ha explicado la diferencia entre mineral y roca.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37639\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0033\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0033\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-576x1024.jpg\" class=\"alignnone size-large wp-image-37639\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0033.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37616\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240512-wa00042\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042.jpg\" data-orig-size=\"1002,601\" data-comments-opened=\"1\" data-image-title=\"IMG-20240512-WA0004~2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042.jpg\" class=\"alignnone size-full wp-image-37616\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042.jpg\" alt=\"\" width=\"1002\" height=\"601\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042.jpg 1002w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042-300x180.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00042-768x461.jpg 768w\" sizes=\"(max-width: 1002px) 100vw, 1002px\" \/><\/p>\n<p><strong>\u00bfQu\u00e9 es un mineral?\u00a0<\/strong><\/p>\n<p>Un mineral es una sustancia inorg\u00e1nica y s\u00f3lida con una estructura cristalina. Ejemplos de minerales incluyen al jaspe d\u00e1lmata, turquesa, ojo de tigre, sodalita, cuarzo rosa, venturina. Sus ejemplares han sido pulidos, ahora son suaves.<\/p>\n<p>Adam nos muestra sus ejemplares de minerales y su libro \u201cRock Tumbler Learning Guide.\u201d<img decoding=\"async\" data-attachment-id=\"37633\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0022\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0022\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-1024x576.jpg\" class=\"alignnone size-large wp-image-37633\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0022.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37612\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/screenshot_2024-05-12-14-23-42-662_com-microsoft-office-officehubrow2\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2.jpg\" data-orig-size=\"1080,618\" data-comments-opened=\"1\" data-image-title=\"Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow~2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2-1024x586.jpg\" class=\"alignnone size-large wp-image-37612\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2-1024x586.jpg\" alt=\"\" width=\"474\" height=\"271\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2-1024x586.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2-300x172.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2-768x439.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/Screenshot_2024-05-12-14-23-42-662_com.microsoft.office.officehubrow2.jpg 1080w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>No es dif\u00edcil cultivar cristales en casa. \u00a1Se pueden cultivar en una semana!<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37641\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0023\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0023\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-576x1024.jpg\" class=\"alignnone size-large wp-image-37641\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0023.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37613\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240512-wa00022\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022.jpg\" data-orig-size=\"1038,1162\" data-comments-opened=\"1\" data-image-title=\"IMG-20240512-WA0002~2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022-915x1024.jpg\" class=\"alignnone size-large wp-image-37613\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022-915x1024.jpg\" alt=\"\" width=\"474\" height=\"530\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022-915x1024.jpg 915w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022-268x300.jpg 268w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022-768x860.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00022.jpg 1038w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><strong>\u00bfQu\u00e9 es una roca?<\/strong><\/p>\n<p>Las rocas son partes s\u00f3lidas de la tierra y pueden ser muy diferentes entre s\u00ed. Est\u00e1n compuestas<\/p>\n<p>por varios minerales que se forman naturalmente con el tiempo, durante millones de a\u00f1os.<\/p>\n<p>Hay tres clasificaciones de las rocas: \u00cdgneas, metam\u00f3rficas y sedimentarias. Rocas<\/p>\n<p>\u00edgneas se forman a partir del magma. Rocas metam\u00f3rficas se producen a partir de otras rocas. Las Rocas sedimentarias se forman a partir de sedimentos, como en un r\u00edo. Esas rocas son parte de mi colecci\u00f3n de rocas. Las he encontrado en parques, en bosques, en calles, por todas partes.<\/p>\n<p>Adam\u00a0 nos muestra\u00a0 sus ejemplares de rocas.<img decoding=\"async\" data-attachment-id=\"37634\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0021\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0021\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-576x1024.jpg\" class=\"alignnone size-large wp-image-37634\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0021.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Le gusta que cada roca sea distinta. \u00bfDe qu\u00e9 color es? \u00bfEs rugosa o suave? \u00bfDe qu\u00e9 forma es?<\/p>\n<p>Un ge\u00f3logo\/una ge\u00f3loga es una persona que estudia rocas y la tierra.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37614\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240512-wa00013\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013.jpg\" data-orig-size=\"1034,613\" data-comments-opened=\"1\" data-image-title=\"IMG-20240512-WA0001~3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013-1024x607.jpg\" class=\"alignnone size-large wp-image-37614\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013-1024x607.jpg\" alt=\"\" width=\"474\" height=\"281\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013-1024x607.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013-300x178.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013-768x455.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00013.jpg 1034w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37636\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0030\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0030\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-1024x576.jpg\" class=\"alignnone size-large wp-image-37636\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0030.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><strong>De rocas a piedras preciosas\u00a0<\/strong><\/p>\n<p>Las rocas y minerales no s\u00f3lo son cosas de ciencia. Como seres humanos, nos gustan algunos minerales y rocas m\u00e1s que otros. Nos muestra\u00a0 piedras preciosas.<\/p>\n<p>Piedras preciosas normalmente son de minerales, pero puede ser de rocas tambi\u00e9n. Las usamos para joyer\u00eda o para decoraci\u00f3n.<\/p>\n<p>Muchas veces las rocas en un r\u00edo o en el mar son muy suaves y brillantes. Es porque durante muchos a\u00f1os el agua y arena en el agua han rozado las rocas.<\/p>\n<p>Adam\u00a0 nos muestra una m\u00e1quina que puede hacer ese\u00a0 trabajo\u00a0 y\u00a0 la pone a funcionar.<\/p>\n<p>Con esta m\u00e1quina se puede lograr el mismo efecto. Pongo las rocas \u00e1speras\u00a0 dentro con un polvo especial. La m\u00e1quina gira y las rocas caen y despu\u00e9s de un mes el resultado son piedras lisas y brillantes.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37640\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0024\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0024\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-576x1024.jpg\" class=\"alignnone size-large wp-image-37640\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0024.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37615\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240512-wa00012\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012.jpg\" data-orig-size=\"1038,1181\" data-comments-opened=\"1\" data-image-title=\"IMG-20240512-WA0001~2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012-900x1024.jpg\" class=\"alignnone size-large wp-image-37615\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012-900x1024.jpg\" alt=\"\" width=\"474\" height=\"539\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012-900x1024.jpg 900w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012-264x300.jpg 264w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012-768x874.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240512-WA00012.jpg 1038w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p><strong>Piedras de Nacimiento\u00a0<\/strong><\/p>\n<p>Cada mes est\u00e1 asociado con una roca diferente. Cada roca tiene caracter\u00edsticas o \u201cpoderes\u201d<\/p>\n<p>diferentes. (No es cient\u00edfico, s\u00f3lo divertido.) Algunos meses tienen m\u00e1s de una.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"37632\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0029\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0029\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-1024x576.jpg\" class=\"alignnone size-large wp-image-37632\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0029.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Mi cumple es en diciembre, y mi piedra de nacimiento es la turquesa. El cumple de Dar\u00eda es en abril, y su piedra es el diamante. \u00a1Busca la tuya!<\/p>\n<p>Adam dice a cada compa\u00f1ero cual es su piedra seg\u00fan el mes de nacimiento.<img decoding=\"async\" data-attachment-id=\"37637\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0028\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0028\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-576x1024.jpg\" class=\"alignnone size-large wp-image-37637\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0028.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Felicitamos a Adam por el esfuerzo que ha realizado para compartir con nosotros su investigaci\u00f3n sobre los minerales que tanto le apasionan.<\/p>\n<ul>\n<li>Continuamos con el estudio de los materiales cuyo descubrimiento y uso facilit\u00f3 la evoluci\u00f3n de la humanidad con la\u00a0 mejora de su vida.<\/li>\n<\/ul>\n<h5><strong><span style=\"color: #008000\"> Conferencia Metales preciosos por Gael<\/span><\/strong><\/h5>\n<p>Gael nos\u00a0 ha hablado sobre metales preciosos como el cobre, la plata y el oro, nos ha explicado que se llaman as\u00ed por su valor y porque son muy resistentes a la corrosi\u00f3n.<img decoding=\"async\" data-attachment-id=\"37653\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0006\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0006\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-1024x576.jpg\" class=\"alignnone size-large wp-image-37653\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0006.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Los metales est\u00e1n en la naturaleza en forma de minerales y para convertirlos en metales preciosos tenemos que encontrarlos, extraerlos de la tierra con herramientas especiales y fundirlos.<\/p>\n<p>Hay varias formas de extraerlos, por ejemplo, en los r\u00edos se usan una especie de coladores para separar las piedras del r\u00edo de las pepitas de oro.<\/p>\n<p>Otras veces se usan detectores de metales como el que nos ense\u00f1a , que te dice qu\u00e9 tipo de metal ha encontrado. Por ejemplo, si apunto a una piedra brillante que parece plata, no pita porque es s\u00f3lo una piedra, pero si apunto a un\u00a0 lingote de plata me avisa que es plata.<\/p>\n<p>Cuando en un lugar hay much\u00edsimo oro, plata o cobre, se crea una mina, que es un lugar especializado donde se hacen agujeros enormes en la tierra para extraer los minerales.<img decoding=\"async\" data-attachment-id=\"37658\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0009\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009.jpg\" data-orig-size=\"2048,1579\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0009\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-1024x790.jpg\" class=\"alignnone size-large wp-image-37658\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-1024x790.jpg\" alt=\"\" width=\"474\" height=\"366\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-1024x790.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-300x231.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-768x592.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009-1536x1184.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0009.jpg 2048w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Gael visit\u00f3 la antigua mina de Rodalquilar, en Almer\u00eda donde antes extra\u00edan el oro con qu\u00edmicos, luego lo llevaban a unos especies de coladores gigantes para separar las pepitas de oro de otros minerales y luego los fund\u00edan en lingotes de oro.<\/p>\n<p><strong><span style=\"color: #993300\">Cobre<\/span><\/strong><\/p>\n<p>Es el que m\u00e1s se usa porque es el m\u00e1s barato. Es un metal entre naranja y cobre.<img decoding=\"async\" data-attachment-id=\"37657\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0011\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011.jpg\" data-orig-size=\"2048,1438\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0011\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-1024x719.jpg\" class=\"alignnone size-large wp-image-37657\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-1024x719.jpg\" alt=\"\" width=\"474\" height=\"333\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-1024x719.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-300x211.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-768x539.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011-1536x1079.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0011.jpg 2048w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Chile es el pa\u00eds que m\u00e1s cobre exporta del mundo entero!<\/p>\n<p>El cobre se usa mucho para construir casas, por ejemplo en los cables porque es muy buen conductor de la electricidad. Nos muestra un trozo de cable para ver el cobre por dentro. Y nos lo ense\u00f1a\u00a0 con un experimento que he hecho para\u00a0 ver c\u00f3mo transmite la electricidad.<img decoding=\"async\" data-attachment-id=\"37655\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0004\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0004\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-576x1024.jpg\" class=\"alignnone size-large wp-image-37655\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0004.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Tambi\u00e9n se usa en las tuber\u00edas de agua porque es muy resistente y no se oxida. Nos muestra un trocito de tuber\u00eda de cobre, por dentro pasa el agua. Una casa puede llegar a tener hasta 200 kilos de cobre. Los ordenadores y los tel\u00e9fonos m\u00f3viles contienen cobre para poder funcionar. Un coche nuevo tiene unos 22 kilos de cobre.<\/p>\n<p>A los grandes chefs de cocina les encantan las sartenes y ollas de cobre porque calientan muy r\u00e1pido. El cobre se usa desde la prehistoria!<\/p>\n<p>Adem\u00e1s el cobre se puede reciclar de forma ilimitada! Cuando una sart\u00e9n de cobre se hace vieja, esa s\u00ed que se puede reciclar!! Cuando una casa est\u00e1 vieja y la derrumban para construir una nueva, se puede llevar todo el cobre a reciclar para volver a usarlo.<\/p>\n<p>El cobre tiene propiedades muy necesarias para los seres humanos y est\u00e1 en muchos alimentos: las almejas, las legumbres, las nueces, los anacardos y hasta en el chocolate! El Chile en polvo tiene cobre, pero no el pa\u00eds, el picante mejicano!<\/p>\n<p>Las monedas de la Uni\u00f3n Europea tambi\u00e9n tienen cobre, como la moneda de 5 c\u00e9ntimos que nos ense\u00f1a.<\/p>\n<p><strong>Plata<img decoding=\"async\" data-attachment-id=\"37660\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0010\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010.jpg\" data-orig-size=\"2048,1591\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0010\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-1024x796.jpg\" class=\"alignnone size-large wp-image-37660\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-1024x796.jpg\" alt=\"\" width=\"474\" height=\"368\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-1024x796.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-300x233.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-768x597.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010-1536x1193.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0010.jpg 2048w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/strong><\/p>\n<p>La plata es un metal gris y brillante, refleja s\u00faper bien la luz. Podr\u00edamos hacer un espejo de plata pero costar\u00eda mucho dinero!<\/p>\n<p>En la naturaleza la plata puede parecer una simple piedra. M\u00e9xico y Per\u00fa son los mayores productores de plata del mundo.<\/p>\n<p>La plata se usa mucho en joyer\u00eda para hacer collares, pulseras, anillos&#8230;Pero tambi\u00e9n se usa para hacer cubiertos, platos y bandejas porque es muy bonita y resistente a la corrosi\u00f3n. Adem\u00e1s es s\u00faper f\u00e1cil de limpiar con un poco de agua caliente, bicarbonato y vinagre.<\/p>\n<p>Donde m\u00e1s se usa la plata es en la industria porque transmite muy bien la electricidad y calor, incluso mejor que el cobre, pero es mucho m\u00e1s cara y por eso la plata se usa en productos m\u00e1s especiales como los circuitos y las bater\u00edas de los m\u00f3viles, los ordenadores m\u00e1s caros y los coches el\u00e9ctricos que andan sin gasolina.<\/p>\n<p>Las placas solares y las soldaduras llevan plata porque es muy resistente al calor.<\/p>\n<p>La plata es important\u00edsima en la medicina por sus propiedades antibacterianas. Es capaz de matar algunos tipos de bacterias y virus y curar enfermedades. Se usa para desinfectar el agua y que se pueda beber.<\/p>\n<p>Antiguamente las monedas estaban hechas de plata, incluso de oro pero hoy se usa para ahorrar dinero en forma de lingotes como el que nos ense\u00f1a que pesa un Kg. \u00bfY c\u00f3mo se ahorra? Si tu te compras plata hoy por 10 euros y con los a\u00f1os sube su precio a 20 euros, ganas 10 euros! \u00bfVerdad? Eso con el dinero no pasa. Un billete de 10 euros va a valer siempre 10 euros!<\/p>\n<p><strong>Oro<img decoding=\"async\" data-attachment-id=\"37654\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0008\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008.jpg\" data-orig-size=\"2048,1609\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0008\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-1024x805.jpg\" class=\"alignnone size-large wp-image-37654\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-1024x805.jpg\" alt=\"\" width=\"474\" height=\"373\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-1024x805.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-300x236.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-768x603.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008-1536x1207.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0008.jpg 2048w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/strong><\/p>\n<p>El oro es amarillo y brillante, es el que m\u00e1s brilla. Se suele encontrar en forma de pepitas y de polvo.<\/p>\n<p>Es el m\u00e1s caro y no es porque haya poco, sino porque es dificil\u00edsimo extraerlo!!! Se cree que todo el oro del universo se form\u00f3 por una colisi\u00f3n de estrellas y termin\u00f3 en el n\u00facleo de la tierra. Por eso a veces el oro sale de los volcanes en erupci\u00f3n.<\/p>\n<p>China es el principal pa\u00eds productor de oro.<\/p>\n<p>El oro ha sido siempre un metal muy deseado. Al ser tan caro, el uso principal del oro es en forma de lingotes o monedas para ahorrar dinero como la plata.<\/p>\n<p>Despu\u00e9s, donde m\u00e1s se usa es en joyer\u00eda y decoraci\u00f3n. Se cree que a\u00fan hay 6.000 millones de euros en tesoros perdidos en el mar. \u00a1Yo quisiera encontrar uno!<\/p>\n<p>Es el metal m\u00e1s deseado en las olimpiadas. \u00a1Solo el mejor gana la medalla de oro! Y es tan caro que ni las medallas de oro son realmente de oro.<\/p>\n<p>Tambi\u00e9n se usa en electr\u00f3nica sobre todo en los tel\u00e9fonos m\u00f3viles m\u00e1s potentes! En realidad el oro tiene unos usos muy parecidos a la plata pero m\u00e1s caro. Casi todos los m\u00f3viles m\u00e1s potentes tienen oro.<\/p>\n<p>\u00a1El oro tambi\u00e9n se usa en los cohetes! \u00bfHab\u00e9is visto cu\u00e1nto fuego echan al despegar? \u00a1Gracias al oro el cohete est\u00e1 protegido del fuego de los motores, el oro es el material que mejor aisla el calor!<img decoding=\"async\" data-attachment-id=\"37656\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0003\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003.jpg\" data-orig-size=\"1408,2048\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0003\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-704x1024.jpg\" class=\"alignnone size-large wp-image-37656\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-704x1024.jpg\" alt=\"\" width=\"474\" height=\"689\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-704x1024.jpg 704w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-206x300.jpg 206w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-768x1117.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003-1056x1536.jpg 1056w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0003.jpg 1408w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Nos propone hacer un peque\u00f1o experimento de c\u00f3mo se extrae el oro: unos coladores, y\u00a0 arena y\u00a0 a intentar encontrar las pepitas de oro!!!<\/p>\n<p>No es realmente oro&#8230;. es pirita!! que es un mineral que se le parece mucho, pero no es tan brillante.<\/p>\n<p>Hemos\u00a0 podido ver un lingote de plata,\u00a0 escuchar el sonido del detector de metales al acercarse a un metal escondido, hemos visto c\u00f3mo el cobre conduce la electricidad, c\u00f3mo se separaran las rocas de las pepitas de oro con el colador y c\u00f3mo buscar y separa la plata de las rocas. Nos ha encantado la experimentaci\u00f3n .<img decoding=\"async\" data-attachment-id=\"37659\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240518-wa0007\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-title=\"IMG-20240518-WA0007\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-576x1024.jpg\" class=\"alignnone size-large wp-image-37659\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-576x1024.jpg\" alt=\"\" width=\"474\" height=\"843\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-576x1024.jpg 576w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-169x300.jpg 169w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-768x1365.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007-864x1536.jpg 864w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240518-WA0007.jpg 1125w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Muchas gracias Gael por compartir con nosotros tu investigaci\u00f3n , el inter\u00e9s\u00a0 mostrado y la emoci\u00f3n al transmitir este tema que te apasiona.<\/p>\n<h5><span style=\"color: #993300\"><strong>La prehistoria<\/strong><\/span> ,colaboraci\u00f3n de Vanesa, madre de Alma compa\u00f1era de segundo.<\/h5>\n<p>Hemos tenido la oportunidad de conocer y vivenciar la prehistoria a trav\u00e9s\u00a0 la conferencia y gymkhana propuesta por Vanesa , especialista en historia del arte. <img decoding=\"async\" data-attachment-id=\"37629\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240515-wa0008\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-title=\"IMG-20240515-WA0008\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-1024x768.jpg\" class=\"alignnone size-large wp-image-37629\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-1024x768.jpg\" alt=\"\" width=\"474\" height=\"356\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-1024x768.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-300x225.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-768x576.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008-1536x1152.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240515-WA0008.jpg 1600w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Nos ha propuesto\u00a0 hacer una Gymkhana, en\u00a0 equipos.<\/p>\n<p>Tras contestar unas preguntas\u00a0 sobre c\u00f3mo se viv\u00eda en la prehistoria nos hemos ido al jard\u00edn a investigar como aut\u00e9nticos paleont\u00f3logos buscando indicios que dejaron de su paso por la vega . <img decoding=\"async\" data-attachment-id=\"37662\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240519-wa0000\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240519-WA0000\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-1024x576.jpg\" class=\"alignnone size-large wp-image-37662\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0000.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/> <img decoding=\"async\" data-attachment-id=\"37663\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240519-wa0001\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240519-WA0001\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-1024x576.jpg\" class=\"alignnone size-large wp-image-37663\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0001.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/> <img decoding=\"async\" data-attachment-id=\"37664\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/img-20240519-wa0002\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002.jpg\" data-orig-size=\"2000,1125\" data-comments-opened=\"1\" data-image-title=\"IMG-20240519-WA0002\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-1024x576.jpg\" class=\"alignnone size-large wp-image-37664\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-1024x576.jpg\" alt=\"\" width=\"474\" height=\"267\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-1024x576.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-300x169.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-768x432.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002-1536x864.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/IMG-20240519-WA0002.jpg 2000w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Cada equipo encuentra unas bolsas con objetos relacionados con oficios o alguna funci\u00f3n que hac\u00edan los humanos de la Prehistoria, cuando las han encontrado todas\u00a0 hemos ido preguntando .<img decoding=\"async\" data-attachment-id=\"37661\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/image0-2\/\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/image0.jpeg\" data-orig-size=\"480,640\" data-comments-opened=\"1\" data-image-title=\"image0\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/image0.jpeg\" class=\"alignnone size-full wp-image-37661\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/image0.jpeg\" alt=\"\" width=\"480\" height=\"640\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/image0.jpeg 480w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2024\/05\/image0-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>\u00bfQui\u00e9n es ganadero, Agricultor, Cazador, Quien hace tejidos, Artesano, Qui\u00e9n hace el fuego? Hemos ido descubriendo como viv\u00edan los humanos de la prehistoria gracias a los restos encontrados.<\/p>\n<p>Nos ha encantado la actividad.<\/p>\n<p>Agradecemos a Vanesa su\u00a0 generosa colaboraci\u00f3n y la propuesta de convertirnos\u00a0 en paleont\u00f3logos.<\/p>\n<p><span style=\"color: #800080\"><strong>Art\u00edstica<\/strong><\/span><\/p>\n<p>En art\u00edstica trabajamos como artistas primitivos conociendo sus t\u00e9cnicas, materiales e im\u00e1genes que representa a en las cuevas.<\/p>\n<p>La arcilla ,que nos encanta , se convierte en el material a modelar para conseguir cuentas de diferentes formas para componer collares muy primitivos.<\/p>\n<p>Pintura, pincel, manos , han decorado nuestra cavidad particular .<\/p>\n<p>Todos estos trabajos tendr\u00e1n una funci\u00f3n muy especial para decorar en la fiesta de fin de curso el pr\u00f3ximo 8 de junio con la tem\u00e1tica Prehistoria.<\/p>\n<ul>\n<li>En la siguiente entrada os adelanto informaci\u00f3n sobre la salida a Pi\u00f1ar.<\/li>\n<\/ul>\n<p>Un saludo<\/p>\n<p>Dar\u00eda F.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Prehistoria Seguimos inmersos en el estudio de la prehistoria, sabemos que no hay nada escrito que nos pueda confirmar c\u00f3mo era la vida humana\u00a0 en esa etapa pero somos conocedores\u00a0 que\u00a0 la arqueolog\u00eda, junto a otras ciencias\u00a0 como la geolog\u00eda, la paleontolog\u00eda, la qu\u00edmica o la f\u00edsica, que nos permiten obtener informaci\u00f3n del pasado &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2024\/05\/19\/la-prehistoria-minerales\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">La prehistoria, minerales.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,174,8],"tags":[32,37,60,92],"class_list":["post-37608","post","type-post","status-publish","format-standard","hentry","category-1o-epo","category-conferencias","category-diario-de-clase-1o","tag-alqueria","tag-conferencias","tag-primaria","tag-semanario"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lvS0-9MA","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/37608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/comments?post=37608"}],"version-history":[{"count":2,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/37608\/revisions"}],"predecessor-version":[{"id":37695,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/37608\/revisions\/37695"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/media?parent=37608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/categories?post=37608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/tags?post=37608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}