{"id":3913,"date":"2013-11-21T09:10:16","date_gmt":"2013-11-21T09:10:16","guid":{"rendered":"http:\/\/alqueriaprimerciclo.wordpress.com\/?p=3913"},"modified":"2013-11-21T09:10:16","modified_gmt":"2013-11-21T09:10:16","slug":"el-reciclaje-en-el-aula","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/","title":{"rendered":"El reciclaje en el aula"},"content":{"rendered":"<p>El reciclaje est\u00e1 integrado en la vida cotidiana de nuestro centro. Tenemos la certificaci\u00f3n de Centro Medio Ambiental. Pero eso son palabras mayores para la vida de un ni\u00f1o.<\/p>\n<p>Lo realmente importante es que el reciclaje es un h\u00e1bito gracias a la pr\u00e1ctica cotidiana de la separaci\u00f3n de materiales y correcto almacenaje selectivo de lo que ya no vamos a utilizar. El ejemplo de los adultos en la escuela como en casa, es lo verdaderamente educativo.<a href=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122.jpg\"><img decoding=\"async\" data-attachment-id=\"3920\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/dsc08122\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-title=\"DSC08122\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122-1024x768.jpg\" class=\"alignright size-medium wp-image-3920\" alt=\"DSC08122\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122.jpg?w=300\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122.jpg 1024w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08122-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343.jpg\"><img decoding=\"async\" data-attachment-id=\"3915\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/dsc08343\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-title=\"DSC08343\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343-1024x768.jpg\" class=\"size-medium wp-image-3915 alignleft\" alt=\"DSC08343\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343.jpg?w=300\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343.jpg 1024w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08343-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Para conseguirlo en el aula tenemos contenedores fijos: papel, pl\u00e1stico y tapones.<\/p>\n<p>Clasificaci\u00f3n del papel: papel \u00a0limpio para trabajar, \u00a0reutilizable para borradores o juego de papiroflexia y papel para reciclar en un contenedor. Dos veces al mes vienen a recoger el papel de los contenedores. Hay turnos entre las clases para recogerlo y ponerlo en el contenedor azul. Es muy importante no tirar nada en \u00e9l que no sea papel. La selecci\u00f3n debe ser perfecta, para que podamos mantener este servicio municipal.<a href=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341.jpg\"><img decoding=\"async\" data-attachment-id=\"3918\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/dsc08341\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-title=\"DSC08341\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341-1024x768.jpg\" class=\"alignright size-medium wp-image-3918\" alt=\"DSC08341\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341.jpg?w=300\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341.jpg 1024w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08341-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pl\u00e1stico: los embalajes, bolsas, recipientes de este material van a su contenedor espec\u00edfico. En muchos casos es reutilizable .<\/p>\n<p>Tapones de pl\u00e1stico: \u00a0pueden ser de cualquier tama\u00f1o, forma y color. Esta recogida tiene el objetivo de colaborar en las campa\u00f1as de ayuda a la investigaci\u00f3n de tratamientos para \u00a0enfermedades raras.<\/p>\n<p>El \u00e1rea de art\u00edstica y diferentes talleres de Conocimiento del Medio reutilizan materiales diversos para \u00a0sus actividades.<\/p>\n<p>La recogida de material est\u00e1 bien organizada para evitar tener rincones con una aspecto inadecuado.<\/p>\n<p>El alumnado recibe una charla para recordar la importancia de reciclar y la forma correcta de hacerlo una vez durante el curso por parte del Ayuntamiento.<a href=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314.jpg\"><img decoding=\"async\" data-attachment-id=\"3916\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/dsc08314\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-title=\"DSC08314\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314-1024x768.jpg\" class=\"alignright size-medium wp-image-3916\" alt=\"DSC08314\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314.jpg?w=300\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314.jpg 1024w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2013\/11\/dsc08314-300x225.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El primer ciclo la ha tenido esta semana. En ella se ha tratado adem\u00e1s la importancia de cuidar la ciudad, la forma de hacerlo y c\u00f3mo se organiza.<\/p>\n<p>Pedimos la colaboraci\u00f3n de todos para mantener y fomentar este h\u00e1bito<\/p>\n<p>Dar\u00eda Fen\u00e1ndez y Rosi R\u00e0fols,<\/p>\n<p>Tutoras de primer ciclo de primaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reciclaje est\u00e1 integrado en la vida cotidiana de nuestro centro. Tenemos la certificaci\u00f3n de Centro Medio Ambiental. Pero eso son palabras mayores para la vida de un ni\u00f1o. Lo realmente importante es que el reciclaje es un h\u00e1bito gracias a la pr\u00e1ctica cotidiana de la separaci\u00f3n de materiales y correcto almacenaje selectivo de lo &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2013\/11\/21\/el-reciclaje-en-el-aula\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">El reciclaje en el aula<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,3],"tags":[],"class_list":["post-3913","post","type-post","status-publish","format-standard","hentry","category-1o-epo","category-2o-epo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lvS0-117","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/3913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/comments?post=3913"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/3913\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/media?parent=3913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/categories?post=3913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/tags?post=3913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}