{"id":8066,"date":"2015-05-29T12:45:43","date_gmt":"2015-05-29T10:45:43","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/?p=8066"},"modified":"2015-05-29T12:45:43","modified_gmt":"2015-05-29T10:45:43","slug":"una-tarde-en-el-museo","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2015\/05\/29\/una-tarde-en-el-museo\/","title":{"rendered":"Una tarde en el museo"},"content":{"rendered":"<h3>Volvemos a practicar:<\/h3>\n<p>Esta semana transcribimos gran parte de nuestros aprendizajes en el cuaderno de viaje, sobre la experiencia vivida en P\u00ed\u00f1ar.\u00a0Son muchos los conocimientos que hemos adquirido y nos sentimos muy satisfechos.<\/p>\n<h4>Matem\u00e1ticas<\/h4>\n<p><img decoding=\"async\" class=\" alignleft\" src=\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcSDBbCbU6EinH0zvV-HxCeAsjdpF0yaq0axayX9FdlVnq60TJq6bg\" alt=\"Resultado de imagen de calculando\" \/>Volvemos a las tareas peri\u00f3dicas de matem\u00e1ticas. Queda muy poco tiempo para acabar el curso y es conveniente repasar el sistema de numeraci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 ( unidades- decenas), El c\u00e1lculo mental con n\u00fameros de una y dos cifras, completar el cuaderno de Siete y Medio y el \u00a0de problemas.<\/p>\n<h4>Escritura<img decoding=\"async\" class=\" alignright\" src=\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcRMnpa7MRTROIoG8WAMObQq0vJmQn5m73QYxkDfKYO3l8120NN_UQ\" alt=\"Resultado de imagen de escribiendo\" \/><\/h4>\n<p>Revisamos la ortograf\u00eda que hemos estado utilizado \u00a0y las partes que debe tener\u00a0\u00a0el texto escrito\u00a0para mejorar la comunicaci\u00f3n. Estamos en la \u00faltima letra del cuaderno de Diccionario.<\/p>\n<h4><img decoding=\"async\" class=\" alignleft\" src=\"https:\/\/encrypted-tbn1.gstatic.com\/images?q=tbn:ANd9GcT1XaaFSFc1n6hKlGMU_HyPOtS1Indh3GBJ3LzeDBpLgGDNonW0Vw\" alt=\"Resultado de imagen de leyendo\" \/>Lectura<\/h4>\n<p>Cerramos el servicio de pr\u00e9stamo de la biblioteca, para proceder a su revisi\u00f3n e inventario. Debemos procurar que ning\u00fan libro se quede en casa sin devolver.<\/p>\n<p>Ahora aprovecharemos para \u00a0llevar nuestros propios libros a clase para seguir practicando.<\/p>\n<p>Terminamos la lectura en voz alta de<em> El principito<\/em>, de Antoine de Saint Exup\u00e9ry que nos ha acompa\u00f1ado a lo largo del curso.<\/p>\n<h4>Art\u00edstica<\/h4>\n<p>Construimos pistas para nuestros mu\u00f1ecos.<\/p>\n<p><img decoding=\"async\" data-attachment-id=\"8073\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2015\/05\/29\/una-tarde-en-el-museo\/dsc01900\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01900.jpg\" data-orig-size=\"1024,575\" data-comments-opened=\"1\" data-image-title=\"DSC01900\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01900-1024x575.jpg\" class=\"aligncenter size-medium wp-image-8073\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01900-300x168.jpg\" alt=\"DSC01900\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01900-300x168.jpg 300w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01900.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" data-attachment-id=\"8072\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2015\/05\/29\/una-tarde-en-el-museo\/dsc01901\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01901.jpg\" data-orig-size=\"1024,575\" data-comments-opened=\"1\" data-image-title=\"DSC01901\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01901-1024x575.jpg\" class=\"aligncenter size-medium wp-image-8072\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01901-300x168.jpg\" alt=\"DSC01901\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01901-300x168.jpg 300w, https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-content\/uploads\/sites\/6\/2015\/05\/DSC01901.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4>Preparamos la fiesta<\/h4>\n<h2 style=\"text-align: center\">\u00bb Una tarde en el museo\u00bb<\/h2>\n<p><img decoding=\"async\" class=\" aligncenter\" src=\"https:\/\/encrypted-tbn3.gstatic.com\/images?q=tbn:ANd9GcSKnkrHDxzB62GPujEzO9u7F8877OO3xWYxJ0p2S9MykERc2FR8lA\" alt=\"Resultado de imagen de una tarde en el museo\" \/><\/p>\n<p>El s\u00e1bado d\u00eda 30 de mayo a las 6, 30h., vamos a celebrar la fiesta de final de curso. Esperamos que nos acompa\u00f1\u00e9is y disfrut\u00e9is de una tarde agradable con todos nosotros.<\/p>\n<p>Os deseamos un buen fin de semana<br \/>\nRosi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volvemos a practicar: Esta semana transcribimos gran parte de nuestros aprendizajes en el cuaderno de viaje, sobre la experiencia vivida en P\u00ed\u00f1ar.\u00a0Son muchos los conocimientos que hemos adquirido y nos sentimos muy satisfechos. Matem\u00e1ticas Volvemos a las tareas peri\u00f3dicas de matem\u00e1ticas. Queda muy poco tiempo para acabar el curso y es conveniente repasar el sistema &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/2015\/05\/29\/una-tarde-en-el-museo\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Una tarde en el museo<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,8],"tags":[],"class_list":["post-8066","post","type-post","status-publish","format-standard","hentry","category-1o-epo","category-diario-de-clase-1o"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lvS0-266","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/8066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/comments?post=8066"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/posts\/8066\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/media?parent=8066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/categories?post=8066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriaprimerciclo\/wp-json\/wp\/v2\/tags?post=8066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}