{"id":2196,"date":"2013-01-16T10:53:23","date_gmt":"2013-01-16T09:53:23","guid":{"rendered":"http:\/\/alqueriarojaverde.wordpress.com\/?p=2196"},"modified":"2013-01-16T10:53:23","modified_gmt":"2013-01-16T09:53:23","slug":"taller-de-matematicas","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2013\/01\/16\/taller-de-matematicas\/","title":{"rendered":"TALLER DE MATEMATICAS CLASE VERDE"},"content":{"rendered":"<p>Semana del 14 al 18 de enero.<\/p>\n<p>La actividad surgi\u00f3 a partir de la propuesta de que trajeran escrito en un papel\u00a0 la hora en la que se levantan cada d\u00eda. Tambi\u00e9n vimos las horas principales del d\u00eda: la hora de la comida, de la cena y a la hora que nos acostamos.<\/p>\n<p>Hemos trabajado los n\u00fameros\u00a0 y el tiempo a trav\u00e9s del reloj.<\/p>\n<ul>\n<li>Primero hemos escrito los n\u00fameros del 1 al 12.<\/li>\n<li>Los hemos ido pegando en un c\u00edrculo, paralelamente hemos trabajado los conceptos, arriba, abajo, derecha, izquierda, despu\u00e9s, antes etc.<\/li>\n<li>Las manillas del reloj las diferenci\u00e1mos por tama\u00f1os, colocando un c\u00edrculo rojo a la peque\u00f1a que marca las horas.<\/li>\n<\/ul>\n<p>Realizamos varias actividades con carteles de n\u00fameros. Los chicos\/as tienen que poner la hora del n\u00fameroque les ense\u00f1amos. Tambi\u00e9n lo hacemos con las fichas de estimaci\u00f3n.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-2196-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2013\\\/01\\\/el-reloj1.jpg?fit=1024%2C768\\u0026ssl=1&quot;,&quot;id&quot;:&quot;2363&quot;,&quot;title&quot;:&quot;el reloj&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2013\\\/01\\\/fichas-de-estimaciocc81n1.jpg?fit=1024%2C768\\u0026ssl=1&quot;,&quot;id&quot;:&quot;2364&quot;,&quot;title&quot;:&quot;fichas de estimacio\\u0301n&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2013\\\/01\\\/los-numeros1.jpg?fit=768%2C1024\\u0026ssl=1&quot;,&quot;id&quot;:&quot;2365&quot;,&quot;title&quot;:&quot;los numeros&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2013\\\/01\\\/relojes1.jpg?fit=1024%2C768\\u0026ssl=1&quot;,&quot;id&quot;:&quot;2366&quot;,&quot;title&quot;:&quot;relojes&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p>Rosario Garc\u00eda-Valenzuela Morell<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Semana del 14 al 18 de enero. La actividad surgi\u00f3 a partir de la propuesta de que trajeran escrito en un papel\u00a0 la hora en la que se levantan cada d\u00eda. Tambi\u00e9n vimos las horas principales del d\u00eda: la hora de la comida, de la cena y a la hora que nos acostamos. Hemos trabajado &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2013\/01\/16\/taller-de-matematicas\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">TALLER DE MATEMATICAS CLASE VERDE<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,13,14,15],"tags":[],"class_list":["post-2196","post","type-post","status-publish","format-standard","hentry","category-clase-verde-5-6-anos","category-inicio","category-logica-matematica-clase-verde","category-noticias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lFbP-zq","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts\/2196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/comments?post=2196"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts\/2196\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/media?parent=2196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/categories?post=2196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/tags?post=2196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}