{"id":36798,"date":"2022-10-24T15:01:59","date_gmt":"2022-10-24T13:01:59","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/?p=36798"},"modified":"2022-10-24T15:01:59","modified_gmt":"2022-10-24T13:01:59","slug":"verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/","title":{"rendered":"\u00a1VERDURAS GRATINADAS! NUESTRA PRIMERA RECETA DE COCINA DEL CURSO"},"content":{"rendered":"<p>\u00a1Buenas tardes familias!<\/p>\n<p>Nueva semana y nueva actividad a inaugurar<em><strong><span style=\"color: #008000\"> \u00a1nuestros talleres de cocina mensuales!<\/span><\/strong><\/em><\/p>\n<p>Normalmente se celebrar\u00e1n los martes, pero ma\u00f1ana tenemos programado realizar otra sesi\u00f3n de Educaci\u00f3n emocional en el aula, a cargo de nuestra compa\u00f1era Laura (psic\u00f3loga), que junto al ingl\u00e9s ocupar\u00e1 el grueso de la ma\u00f1ana. Adem\u00e1s \u00a0me ausentar\u00e9 unas horas, quedando el grupo a cargo de Magaly.<\/p>\n<p>Nada mejor que educar con el ejemplo \u00bfno? pues poniendo en pr\u00e1ctica la flexibilizaci\u00f3n cognitiva necesaria, intercambiamos programaci\u00f3n, adaptamos talleres y de paso introducimos el elemento sorpresa en clase, que es un excelente recurso para EMOCIONARSE.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"36800\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/dibujo-taller-de-cocina\/\" data-orig-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/dibujo-taller-de-cocina.jpg?fit=700%2C402&amp;ssl=1\" data-orig-size=\"700,402\" data-comments-opened=\"1\" data-image-title=\"dibujo-taller-de-cocina\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/dibujo-taller-de-cocina.jpg?fit=474%2C272&amp;ssl=1\" class=\"aligncenter size-medium wp-image-36800\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/dibujo-taller-de-cocina-300x172.jpg?resize=300%2C172&#038;ssl=1\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/dibujo-taller-de-cocina.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/dibujo-taller-de-cocina.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El tema del \u00abrechazo\u00bb a las verduras gratinadas del men\u00fa es algo que trabajamos de manera recurrente cada vez que toca, ya que no es un plato habitual en el entorno familiar y la gran mayor\u00eda del alumnado se muestra reacio a probarlas. \u00a0Pero nada mejor que cocinar uno mismo lo que se va a comer, para que <strong>\u00absurta efecto la magia\u00bb.<\/strong><\/p>\n<p>Han participado de forma activa en una<em><strong><span style=\"color: #ff0000\"> receta de cocina<\/span><\/strong><\/em>\u00a0muy sencilla que tiene como \u00fanicos ingredientes calabac\u00edn, zanahoria y queso.<\/p>\n<p style=\"text-align: center\"><strong><span style=\"color: #ff0000\">\u00a1Verduras de temporada gratinadas!<\/span><\/strong><\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:8,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/2022\\\/10\\\/24\\\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\\\/&quot;,&quot;likes_blog_id&quot;:64268569}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/20221024_103617\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"36803\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-title=\"20221024_103617\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg?fit=474%2C356&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg 150w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg 466w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_103617.jpg 699w\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"20221024_103617\" alt=\"20221024_103617\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/20221024_112227\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"36822\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-title=\"20221024_112227\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg?fit=474%2C356&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg 150w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg 466w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_112227.jpg 699w\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"20221024_112227\" alt=\"20221024_112227\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <\/div> <\/div>\n<p>&nbsp;<\/p>\n<p>Han colaborado en el pelado y rallado de los ingredientes y su posterior mezcla. Adem\u00e1s he tra\u00eddo un mini-horno de casa, de manera que pudiesen ver incluso el proceso de horneado en el aula.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-36798-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104059.jpg?fit=1500%2C2000\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36804&quot;,&quot;title&quot;:&quot;20221024_104059&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104115.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36805&quot;,&quot;title&quot;:&quot;20221024_104115&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104247.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36806&quot;,&quot;title&quot;:&quot;20221024_104247&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104333.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36807&quot;,&quot;title&quot;:&quot;20221024_104333&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104416.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36808&quot;,&quot;title&quot;:&quot;20221024_104416&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104557.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36809&quot;,&quot;title&quot;:&quot;20221024_104557&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104632.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36810&quot;,&quot;title&quot;:&quot;20221024_104632&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104812.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36811&quot;,&quot;title&quot;:&quot;20221024_104812&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104942.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36812&quot;,&quot;title&quot;:&quot;20221024_104942&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104946.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36813&quot;,&quot;title&quot;:&quot;20221024_104946&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_104951.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36814&quot;,&quot;title&quot;:&quot;20221024_104951&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_105429.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36815&quot;,&quot;title&quot;:&quot;20221024_105429&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_105433.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36816&quot;,&quot;title&quot;:&quot;20221024_105433&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_105548.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36817&quot;,&quot;title&quot;:&quot;20221024_105548&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_105557.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36818&quot;,&quot;title&quot;:&quot;20221024_105557&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_105613.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36819&quot;,&quot;title&quot;:&quot;20221024_105613&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_110444.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36820&quot;,&quot;title&quot;:&quot;20221024_110444&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/10\\\/20221024_110944.jpg?fit=2000%2C1500\\u0026ssl=1&quot;,&quot;id&quot;:&quot;36821&quot;,&quot;title&quot;:&quot;20221024_110944&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p>A la gran mayor\u00eda le ha gustado el resultado, algunos han querido incluso repetir varias veces y tan s\u00f3lo a tres no ha gustado nada de nada.<\/p>\n<p>Debemos educar nuestro paladar y atrevernos por lo menos a probar cosas nuevas, as\u00ed que mientras esperamos el tiempo necesario de horneado hemos tomado junto a nuestra fruta de la ma\u00f1ana, un rico boniato asado.<\/p>\n<p>Antes de ponernos manos a la obra con esta sencilla pero riqu\u00edsima receta, hemos celebrado nuestra habitual <em><strong><span style=\"color: #800080\">asamblea de inicio de semana<\/span><\/strong><\/em> en la que adem\u00e1s de realizar las tareas del s\u00faper-ayudante del d\u00eda, hemos presentado la actividad. Aprovechamos para descubrir si los ingredientes tienen origen animal o vegetal, cu\u00e1l ser\u00e1 el proceso a seguir en la elaboraci\u00f3n&#8230;<\/p>\n<p>Tambi\u00e9n decidimos realizar un <strong><span style=\"color: #ff6600\">mini-taller alfab\u00e9tico,<\/span><\/strong> para copiar los <em><span style=\"color: #ff6600\">ingredientes de la receta<\/span><\/em>, ya que algunos\/as la quieren reproducir en casa <strong>\u00a1les ha encantado!<\/strong><\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:8,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriarojaverde\\\/2022\\\/10\\\/24\\\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\\\/&quot;,&quot;likes_blog_id&quot;:64268569}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/20221024_101726\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"36825\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-title=\"20221024_101726\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg?fit=474%2C356&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg 150w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg 466w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101726.jpg 699w\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"20221024_101726\" alt=\"20221024_101726\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/20221024_101731\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"36802\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg\" data-orig-size=\"2000,1500\" data-comments-opened=\"1\" data-image-title=\"20221024_101731\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg?fit=474%2C356&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg 150w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg 466w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/8\/2022\/10\/20221024_101731.jpg 699w\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"20221024_101731\" alt=\"20221024_101731\" style=\"width: 233px; height: 233px;\" \/> <\/a> <\/div> <\/div> <\/div> <\/div>\n<p>\u00a1Nos vemos ma\u00f1ana!<\/p>\n<p>Esther Justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Buenas tardes familias! Nueva semana y nueva actividad a inaugurar \u00a1nuestros talleres de cocina mensuales! Normalmente se celebrar\u00e1n los martes, pero ma\u00f1ana tenemos programado realizar otra sesi\u00f3n de Educaci\u00f3n emocional en el aula, a cargo de nuestra compa\u00f1era Laura (psic\u00f3loga), que junto al ingl\u00e9s ocupar\u00e1 el grueso de la ma\u00f1ana. Adem\u00e1s \u00a0me ausentar\u00e9 unas horas, &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/2022\/10\/24\/verduras-gratinadas-nuestra-primera-receta-de-cocina-del-curso\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">\u00a1VERDURAS GRATINADAS! NUESTRA PRIMERA RECETA DE COCINA DEL CURSO<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23,7,13],"tags":[1509,936,1508,1507],"class_list":["post-36798","post","type-post","status-publish","format-standard","hentry","category-actividades-especiales-y-salidas-clase-verde","category-clase-verde-5-6-anos","category-inicio","tag-alfabetizacion-significativa","tag-alimentacion-saludable","tag-cocina-en-educacion-infantil","tag-recetas-de-cocina-faciles"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lFbP-9zw","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts\/36798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/comments?post=36798"}],"version-history":[{"count":3,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts\/36798\/revisions"}],"predecessor-version":[{"id":36826,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/posts\/36798\/revisions\/36826"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/media?parent=36798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/categories?post=36798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriarojaverde\/wp-json\/wp\/v2\/tags?post=36798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}