{"id":15558,"date":"2017-01-14T11:02:37","date_gmt":"2017-01-14T10:02:37","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/?p=15558"},"modified":"2017-01-14T11:02:37","modified_gmt":"2017-01-14T10:02:37","slug":"estamos-de-vuelta-seguimos-en-3o","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/estamos-de-vuelta-seguimos-en-3o\/","title":{"rendered":"ESTAMOS DE VUELTA&#8230; seguimos en 3\u00ba"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"color: #000000\">\u00a1Feliz a\u00f1o a todos! He tenido la oportunidad de saludaros personalmente a muchos de vosotros, a los que no, aprovecho y lo hago por aqu\u00ed, dese\u00e1ndoos que este a\u00f1o que acabamos de empezar est\u00e9 cargado de nuevas y buenas experiencias y que disfrut\u00e9is acompa\u00f1ando a vuestros hijos en las suyas propias \u00a1es un placer!<\/span><\/p>\n<p style=\"text-align: left\">Arrancamos nuevo trimestre, con muchas y muy variadas actividades que nos har\u00e1n aprender y disfrutar.<\/p>\n<p style=\"text-align: left\">Os cuento lo que hemos hecho estos d\u00edas para ir calentando y volviendo a la rutina despu\u00e9s de tanto tiempo.<\/p>\n<p style=\"text-align: left\">Le damos la bienvenida a nuestra compa\u00f1era \u00a0Mame Diarra, \u00a1qu\u00e9 alegr\u00eda les ha dado a todos este reeencuentro! Despu\u00e9s de saludarnos, felicitarnos, contarnos un poquito las vacaciones y los regalos que nos han tra\u00eddo, nuestra compa\u00f1era que ha pasado una larga temporada en Senegal, nos cuenta c\u00f3mo ha sido su estancia all\u00ed, nos habla de la cultura de all\u00ed: comida, lengua, religi\u00f3n, costumbres, fiestas, edificaciones, vestimenta&#8230; No puedo deciros a qui\u00e9n le hac\u00eda m\u00e1s ilusi\u00f3n y estaba m\u00e1s entusiasmado con lo que est\u00e1bamos escuchando si a la locutora o al auditorio, que hac\u00edan continuas preguntas muy interesantes y curiosas.<\/p>\n<p style=\"text-align: left\"><b>C\u00e1lculo<\/b><\/p>\n<p style=\"text-align: left\">Empezamos recordando un poquito el c\u00e1lculo mental de los dobles, los triples y los qu\u00edntuples . En papel trabajamos la tabla del 2, del 3 y del 5 con dibujos que nos ayudan a conocer el resultado. Posteriormente \u00a0resolvemos estas tablas de la manera tradicional (2&#215;3=&#8230;; 3&#215;7=&#8230;). Les hemos facilitado una tabla que contiene todas las tablas del 1 al 10, parecido a la tabla de las sumas, pero con los productos. Con ellas aprenden a localizar el resultado, \u00a0y en principio servir\u00e1n de apoyo para resolver, pero es algo que tienen que aprender de memoria, as\u00ed que cuanto antes empiecen&#8230;<\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.actiludis.com\/wp-content\/uploads\/2016\/02\/TABLA-MULTIPLICAR.png\" width=\"393\" height=\"217\" \/><\/p>\n<p style=\"text-align: left\"><strong>Resoluci\u00f3n de problemas<\/strong><\/p>\n<p style=\"text-align: left\">Aprovechando los desdobles, trabajamos la resoluci\u00f3n de problemas con un cambio\u00a0de enfoque en relaci\u00f3n a los mismos, que les permite hacerlo de una forma m\u00e1s aut\u00f3noma para ellos. Lo hacemos utilizando el siguiente recurso.<\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.educa.madrid.org\/web\/cp.loranca.fuenlabrada\/images\/Problematicas%202.jpg\" width=\"359\" height=\"235\" \/><\/p>\n<p style=\"text-align: left\"><strong>Tratamiento de la informaci\u00f3n<\/strong><\/p>\n<p style=\"text-align: left\">El otro d\u00eda recibimos un encargo de parte de F\u00e1tima, quer\u00eda saber cu\u00e1nto eran en el mundo dulce, los a\u00f1os que hab\u00eda cumplido, as\u00ed que nos trajo una bolsa de chuches y nos pidi\u00f3 qu\u00e9 le cont\u00e1semos sus a\u00f1os y se lo dij\u00e9semos (el premio era que nos las comer\u00edamos, mmm).<\/p>\n<p style=\"text-align: left\">Nos pusimos manos \u00a0a la obra. Repart\u00ed a cada grupo una cantidad de chuches variadas que ten\u00edan que conta<span style=\"color: #333333\">r y tambi\u00e9n c\u00faantas de cada clase. Recogimos esa informaci\u00f3n en una <strong>TABLA\u00a0<\/strong>y as\u00ed obtuvimos \u00a0varios resultados. Por un lado pudimos saber cu\u00e1ntas chuches de cada clase hab\u00eda repartido en total, y por otro lad<\/span>o cu\u00e1ntas chuches hab\u00eda repartido y conocer as\u00ed si era la cantidad que est\u00e1bamos buscando. Nos hab\u00edamos \u00abexcedido\u00bb as\u00ed que cada grupo ten\u00eda que dejar una cantidad diferente de nuevo en la bolsa. Una vez ten\u00edamos las justas, hicimos el reparto para los 27, que nos dio la oportunidad de hablar de la divisi\u00f3n por dos cifras (para que vaya sonando).<\/p>\n<div data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/estamos-de-vuelta-seguimos-en-3o\/&quot;}' id='gallery-1' class='gallery galleryid-15558 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4340\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4340-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" data-attachment-id=\"15578\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4340\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4340.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4340\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4340-1024x768.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4341\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4341-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" data-attachment-id=\"15577\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4341\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4341.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4341\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4341-1024x768.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4343\/'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4343-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" data-attachment-id=\"15575\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/semanario-de-4o-semana-del-9-al-13-de-enero\/img_4343\/\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4343.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4343\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4343-1024x768.jpg\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: left\">Hablamos de como podemos representar toda esta informaci\u00f3n de manera que de un solo vistazo podamos hacernos una idea de los datos en general. Esto son las GR\u00c1FICAS, as\u00ed que hacemos las nuestras, en este caso GR\u00c1FICAS DE BARRAS. \u00a0Cre\u00e9dme si os digo que esta no ha sido una tarea f\u00e1cil, pues las han realizado en folio blanco, as\u00ed que han tenido que medir; trazar l\u00edneas rectas, perpendiculares y paralelas usando la regla (no es f\u00e1cil que no se mueva!); trasladar los datos&#8230; y que todo esto quede limpio y ordenado. Pues&#8230; \u00a1LO HAN CONSEGUIDO! Pod\u00e9is ver las gr\u00e1ficas en el tabl\u00f3n exterior del aula.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-15558-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4328-1024x768.jpg&quot;,&quot;id&quot;:&quot;15590&quot;,&quot;title&quot;:&quot;IMG_4328&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4327-1024x768.jpg&quot;,&quot;id&quot;:&quot;15591&quot;,&quot;title&quot;:&quot;IMG_4327&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4326-1024x768.jpg&quot;,&quot;id&quot;:&quot;15592&quot;,&quot;title&quot;:&quot;IMG_4326&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4323-1024x768.jpg&quot;,&quot;id&quot;:&quot;15595&quot;,&quot;title&quot;:&quot;IMG_4323&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4325-1024x768.jpg&quot;,&quot;id&quot;:&quot;15593&quot;,&quot;title&quot;:&quot;IMG_4325&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4319-1-1024x768.jpg&quot;,&quot;id&quot;:&quot;15602&quot;,&quot;title&quot;:&quot;IMG_4319&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4339-1024x768.jpg&quot;,&quot;id&quot;:&quot;15579&quot;,&quot;title&quot;:&quot;IMG_4339&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4330-1024x768.jpg&quot;,&quot;id&quot;:&quot;15588&quot;,&quot;title&quot;:&quot;IMG_4330&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4334-1024x768.jpg&quot;,&quot;id&quot;:&quot;15584&quot;,&quot;title&quot;:&quot;IMG_4334&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4335-1024x768.jpg&quot;,&quot;id&quot;:&quot;15583&quot;,&quot;title&quot;:&quot;IMG_4335&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4336-1024x768.jpg&quot;,&quot;id&quot;:&quot;15582&quot;,&quot;title&quot;:&quot;IMG_4336&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4337-1024x768.jpg&quot;,&quot;id&quot;:&quot;15581&quot;,&quot;title&quot;:&quot;IMG_4337&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4331-1024x768.jpg&quot;,&quot;id&quot;:&quot;15587&quot;,&quot;title&quot;:&quot;IMG_4331&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4321-1024x768.jpg&quot;,&quot;id&quot;:&quot;15597&quot;,&quot;title&quot;:&quot;IMG_4321&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2017\\\/01\\\/IMG_4322-1024x768.jpg&quot;,&quot;id&quot;:&quot;15596&quot;,&quot;title&quot;:&quot;IMG_4322&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p style=\"text-align: left\"><strong>Lectura<\/strong><\/p>\n<p style=\"text-align: left\">Continuamos con la lectura de nuestro libro de fantas\u00eda \u00abRetorno a la Isla Blanca\u00bb. Estamos muy intrigados, \u00danica est\u00e1 llegando al final del camino, \u00bfencontrar\u00e1 la verdadera historia de su familia, los medianos de color azul?<\/p>\n<p style=\"text-align: left\"><strong>Escritura<\/strong><\/p>\n<p style=\"text-align: left\">Recordamos las normas para realizar un texto escrito, lo hacemos con el apoyo de una r\u00fabrica, donde ellos conocen de antemano qu\u00e9 se les est\u00e1 pidiendo y luego pueden comprobar \u00abobjetivamente\u00bb c\u00f3mo lo han hecho cada uno. Empezamos usando esta herramienta nueva con un dictado, que primero leemos todos en grupo y luego realizamos.<\/p>\n<p style=\"text-align: left\"><strong>Reino animal<\/strong><\/p>\n<p style=\"text-align: left\">Empieza un nuevo tema en ciencias, EL REINO ANIMAL. Lo primero que hacemos es una lluvia de ideas (\u00ab\u00bfy eso qu\u00e9 es?\u00bb preguntaban, pues despu\u00e9s de explicarlo&#8230; no paraba de llover!; as\u00ed que lo usaremos mucho). Recogemos esa lluvia de ideas en un esquema, que luego organizamos y le damos forma creando el \u00edndice de nuestro tema de investigaci\u00f3n. Ahora ha llegado el momento de formar parejas y empezar a investigar.<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2017\\\/01\\\/14\\\/estamos-de-vuelta-seguimos-en-3o\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"15572\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4346-e1484388037432.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4346\" data-image-description=\"\" data-medium-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4346-e1484388037432-225x300.jpg\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4346-e1484388037432-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4346-e1484388037432.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_4346\" alt=\"IMG_4346\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"15573\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4345.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4345\" data-image-description=\"\" data-medium-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4345-300x225.jpg\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4345-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4345.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_4345\" alt=\"IMG_4345\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"15571\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4347.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4347\" data-image-description=\"\" data-medium-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4347-300x225.jpg\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4347-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4347.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_4347\" alt=\"IMG_4347\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"15570\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4348-e1484388001497.jpg\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_4348\" data-image-description=\"\" data-medium-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4348-e1484388001497-225x300.jpg\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4348-e1484388001497-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-content\/uploads\/sites\/7\/2017\/01\/IMG_4348-e1484388001497.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_4348\" alt=\"IMG_4348\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<p style=\"text-align: left\">Creo que ha sido una semana muy provechosa, hemos trabajado con mucha ilusi\u00f3n, se nota que han cargado las pilasen este tiempo de vacaciones.<\/p>\n<p style=\"text-align: left\">Ahora toca descansar, leer, disfrutar el fin de semana.<\/p>\n<p style=\"text-align: left\">Laura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Feliz a\u00f1o a todos! He tenido la oportunidad de saludaros personalmente a muchos de vosotros, a los que no, aprovecho y lo hago por aqu\u00ed, dese\u00e1ndoos que este a\u00f1o que acabamos de empezar est\u00e9 cargado de nuevas y buenas experiencias y que disfrut\u00e9is acompa\u00f1ando a vuestros hijos en las suyas propias \u00a1es un placer! Arrancamos &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2017\/01\/14\/estamos-de-vuelta-seguimos-en-3o\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">ESTAMOS DE VUELTA&#8230; seguimos en 3\u00ba<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,59],"tags":[],"class_list":["post-15558","post","type-post","status-publish","format-standard","hentry","category-3o-epo","category-semanario-3o"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lw4c-42W","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/15558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/comments?post=15558"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/15558\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/media?parent=15558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/categories?post=15558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/tags?post=15558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}