{"id":30147,"date":"2024-02-27T17:12:58","date_gmt":"2024-02-27T16:12:58","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/?p=30147"},"modified":"2024-02-27T17:12:58","modified_gmt":"2024-02-27T16:12:58","slug":"carnaval-carnaval-5","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2024\/02\/27\/carnaval-carnaval-5\/","title":{"rendered":"CARNAVAL, CARNAVAL&#8230;"},"content":{"rendered":"<p>\u00a1\u00a1\u00a1Lleg\u00f3 el momento de nuestra gran fiesta de carnaval!!!<\/p>\n<p>Desde primera hora disfrutamos de los disfraces del alumnado,\u00a0 el cole est\u00e1 invadido de color, buen humor y muchos y variados personajes de todos los estilos.<\/p>\n<p>A primera hora aprovechamos para juntarnos los grupos de 3\u00ba y 4\u00ba y compartir nuestros disfraces, nos presentamos y hacemos un mini desfile. Se hacen las \u00abagrupaciones\u00bb que m\u00e1s tarde har\u00e1n una peque\u00f1a \u00abrepresentaci\u00f3n, baile, teatrillo&#8230;\u00bb acorde a sus disfraces.<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2024\\\/02\\\/27\\\/carnaval-carnaval-5\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"gallery-group\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"470\"> <meta itemprop=\"height\" content=\"470\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30192\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/fadc501e-66d7-4b6b-b91e-a472f7ad3dd3.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fadc501e-66d7-4b6b-b91e-a472f7ad3dd3\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/fadc501e-66d7-4b6b-b91e-a472f7ad3dd3-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/fadc501e-66d7-4b6b-b91e-a472f7ad3dd3-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/fadc501e-66d7-4b6b-b91e-a472f7ad3dd3.jpg?w=470&#038;h=470&#038;crop=1&#038;ssl=1\" width=\"470\" height=\"470\" loading=\"lazy\" data-original-width=\"470\" data-original-height=\"470\" itemprop=\"http:\/\/schema.org\/image\" title=\"fadc501e-66d7-4b6b-b91e-a472f7ad3dd3\" alt=\"fadc501e-66d7-4b6b-b91e-a472f7ad3dd3\" style=\"width: 470px; height: 470px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"gallery-group\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"470\"> <meta itemprop=\"height\" content=\"470\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30154\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-23-at-18.25.35-4.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2024-02-23 at 18.25.35-4\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-23-at-18.25.35-4-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-23-at-18.25.35-4-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-23-at-18.25.35-4.jpeg?w=470&#038;h=470&#038;crop=1&#038;ssl=1\" width=\"470\" height=\"470\" loading=\"lazy\" data-original-width=\"470\" data-original-height=\"470\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2024-02-23 at 18.25.35-4\" alt=\"WhatsApp Image 2024-02-23 at 18.25.35-4\" style=\"width: 470px; height: 470px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<p>Salimos al jard\u00edn para hacernos unas bonitas fotos con nuestros disfraces en distintos rincones de este bonito espacio.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-30147-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/f90a4de9-9944-4dba-9fca-a8de411c9aba.jpg&quot;,&quot;id&quot;:&quot;30191&quot;,&quot;title&quot;:&quot;f90a4de9-9944-4dba-9fca-a8de411c9aba&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/36810ede-02ff-42d6-89a0-90388cf48989.jpg&quot;,&quot;id&quot;:&quot;30189&quot;,&quot;title&quot;:&quot;36810ede-02ff-42d6-89a0-90388cf48989&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/65ab3cf7-10d4-4dee-bc6f-a35b5040d13a.jpg&quot;,&quot;id&quot;:&quot;30187&quot;,&quot;title&quot;:&quot;65ab3cf7-10d4-4dee-bc6f-a35b5040d13a&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/006bcc27-e8e4-456f-afda-033ce6783f39.jpg&quot;,&quot;id&quot;:&quot;30185&quot;,&quot;title&quot;:&quot;006bcc27-e8e4-456f-afda-033ce6783f39&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/2edf6086-4339-4618-a6f9-41f181aa9d49.jpg&quot;,&quot;id&quot;:&quot;30184&quot;,&quot;title&quot;:&quot;2edf6086-4339-4618-a6f9-41f181aa9d49&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/2db597a8-8e3a-4d1b-8350-90c70badc808.jpg&quot;,&quot;id&quot;:&quot;30183&quot;,&quot;title&quot;:&quot;2db597a8-8e3a-4d1b-8350-90c70badc808&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.09-4.jpeg&quot;,&quot;id&quot;:&quot;30171&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.09-4&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.08.jpeg&quot;,&quot;id&quot;:&quot;30169&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.08&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.08-4.jpeg&quot;,&quot;id&quot;:&quot;30168&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.08-4&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.08-3.jpeg&quot;,&quot;id&quot;:&quot;30167&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.08-3&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.08-2.jpeg&quot;,&quot;id&quot;:&quot;30166&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.08-2&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.07.jpeg&quot;,&quot;id&quot;:&quot;30165&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.07&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.07-4.jpeg&quot;,&quot;id&quot;:&quot;30164&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.07-4&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.07-3.jpeg&quot;,&quot;id&quot;:&quot;30163&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.07-3&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.06-3.jpeg&quot;,&quot;id&quot;:&quot;30161&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.06-3&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/02\\\/WhatsApp-Image-2024-02-24-at-09.05.06-2.jpeg&quot;,&quot;id&quot;:&quot;30160&quot;,&quot;title&quot;:&quot;WhatsApp Image 2024-02-24 at 09.05.06-2&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p>Tomamos la fruta antes de dar comienzo a la magn\u00edfica fiesta. Empezamos con el pasacalles&#8230;<\/p>\n<div class=\"tiled-gallery type-circle tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2024\\\/02\\\/27\\\/carnaval-carnaval-5\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30193\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/PHOTO-2024-02-24-17-34-26-1536x1003-1.jpg\" data-orig-size=\"1536,1003\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"PHOTO-2024-02-24-17-34-26-1536&amp;#215;1003\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/PHOTO-2024-02-24-17-34-26-1536x1003-1-300x196.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/PHOTO-2024-02-24-17-34-26-1536x1003-1-1024x669.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/PHOTO-2024-02-24-17-34-26-1536x1003-1.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"PHOTO-2024-02-24-17-34-26-1536x1003\" alt=\"PHOTO-2024-02-24-17-34-26-1536x1003\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30177\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.12-2.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2024-02-24 at 09.05.12-2\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.12-2-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.12-2-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.12-2.jpeg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2024-02-24 at 09.05.12-2\" alt=\"WhatsApp Image 2024-02-24 at 09.05.12-2\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30176\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-4.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2024-02-24 at 09.05.11-4\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-4-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-4-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-4.jpeg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2024-02-24 at 09.05.11-4\" alt=\"WhatsApp Image 2024-02-24 at 09.05.11-4\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30175\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-3.jpeg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2024-02-24 at 09.05.11-3\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-3-300x225.jpeg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-3-1024x768.jpeg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/WhatsApp-Image-2024-02-24-at-09.05.11-3.jpeg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2024-02-24 at 09.05.11-3\" alt=\"WhatsApp Image 2024-02-24 at 09.05.11-3\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<p>Llega el momento de comenzar, la m\u00fasica da pie a un colorido y divertido pasacalles. Nos disponemos a escuchar las estupendas comparsas de los grupos de infantil , primaria y las de los profes.\u00a0 Nos divertimos mucho, las letrillas son muy graciosas y provocan las risas y carcajadas de grandes y peque\u00f1os.<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2024\\\/02\\\/27\\\/carnaval-carnaval-5\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"gallery-group\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"470\"> <meta itemprop=\"height\" content=\"470\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30190\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/c1976f14-3b4f-4876-9517-bf1ef5577ff8.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"c1976f14-3b4f-4876-9517-bf1ef5577ff8\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/c1976f14-3b4f-4876-9517-bf1ef5577ff8-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/c1976f14-3b4f-4876-9517-bf1ef5577ff8-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/c1976f14-3b4f-4876-9517-bf1ef5577ff8.jpg?w=470&#038;h=470&#038;crop=1&#038;ssl=1\" width=\"470\" height=\"470\" loading=\"lazy\" data-original-width=\"470\" data-original-height=\"470\" itemprop=\"http:\/\/schema.org\/image\" title=\"c1976f14-3b4f-4876-9517-bf1ef5577ff8\" alt=\"c1976f14-3b4f-4876-9517-bf1ef5577ff8\" style=\"width: 470px; height: 470px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"gallery-group\" style=\"width: 474px; height: 474px;\" data-original-width=\"474\" data-original-height=\"474\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"470\"> <meta itemprop=\"height\" content=\"470\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30186\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/8fe4cd2c-9716-47a5-ab7a-b603c3837362.jpg\" data-orig-size=\"1535,705\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"8fe4cd2c-9716-47a5-ab7a-b603c3837362\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/8fe4cd2c-9716-47a5-ab7a-b603c3837362-300x138.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/8fe4cd2c-9716-47a5-ab7a-b603c3837362-1024x470.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/02\/8fe4cd2c-9716-47a5-ab7a-b603c3837362.jpg?w=470&#038;h=470&#038;crop=1&#038;ssl=1\" width=\"470\" height=\"470\" loading=\"lazy\" data-original-width=\"470\" data-original-height=\"470\" itemprop=\"http:\/\/schema.org\/image\" title=\"8fe4cd2c-9716-47a5-ab7a-b603c3837362\" alt=\"8fe4cd2c-9716-47a5-ab7a-b603c3837362\" style=\"width: 470px; height: 470px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<div class=\"a25-CTUOC-hidding-box\" data-original-content=\"&lt;iframe title=&quot;CHIRIGOTA 3\u00ba&quot; src=&quot;https:\/\/player.vimeo.com\/video\/917049098?dnt=1&amp;amp;app_id=122963&quot; width=&quot;474&quot; height=&quot;268&quot; frameborder=&quot;0&quot; allow=&quot;autoplay; fullscreen; picture-in-picture; clipboard-write&quot;&gt;&lt;\/iframe&gt;\">Esta p\u00e1gina incluye contenido multimedia que requiere aceptar todas las cookies. Pulse aqu\u00ed para abrir la configuraci\u00f3n de cookies.<\/div>\n<div class=\"a25-CTUOC-hidding-box\" data-original-content=\"&lt;iframe title=&quot;CHIRIGOTA 3\u00ba segunda&quot; src=&quot;https:\/\/player.vimeo.com\/video\/917050722?dnt=1&amp;amp;app_id=122963&quot; width=&quot;474&quot; height=&quot;233&quot; frameborder=&quot;0&quot; allow=&quot;autoplay; fullscreen; picture-in-picture; clipboard-write&quot;&gt;&lt;\/iframe&gt;\">Esta p\u00e1gina incluye contenido multimedia que requiere aceptar todas las cookies. Pulse aqu\u00ed para abrir la configuraci\u00f3n de cookies.<\/div>\n<div class=\"a25-CTUOC-hidding-box\" data-original-content=\"&lt;iframe title=&quot;Chirigota 4\u00ba 2023-2024&quot; src=&quot;https:\/\/player.vimeo.com\/video\/917047163?dnt=1&amp;amp;app_id=122963&quot; width=&quot;474&quot; height=&quot;197&quot; frameborder=&quot;0&quot; allow=&quot;autoplay; fullscreen; picture-in-picture; clipboard-write&quot;&gt;&lt;\/iframe&gt;\">Esta p\u00e1gina incluye contenido multimedia que requiere aceptar todas las cookies. Pulse aqu\u00ed para abrir la configuraci\u00f3n de cookies.<\/div>\n<div class=\"a25-CTUOC-hidding-box\" data-original-content=\"&lt;iframe title=&quot;Chirigota 4\u00ba Carnaval 2023-2024&quot; src=&quot;https:\/\/player.vimeo.com\/video\/917049839?dnt=1&amp;amp;app_id=122963&quot; width=&quot;474&quot; height=&quot;215&quot; frameborder=&quot;0&quot; allow=&quot;autoplay; fullscreen; picture-in-picture; clipboard-write&quot;&gt;&lt;\/iframe&gt;\">Esta p\u00e1gina incluye contenido multimedia que requiere aceptar todas las cookies. Pulse aqu\u00ed para abrir la configuraci\u00f3n de cookies.<\/div>\n<p style=\"text-align: center\"><strong>\u00a1<span style=\"color: #00ff00\">ESTO<\/span><span style=\"color: #ff6600\"> S\u00cd<\/span> <span style=\"color: #3366ff\">QUE<\/span> <span style=\"color: #ff00ff\">ES<\/span> <span style=\"color: #ffcc00\">UNA<\/span> <span style=\"color: #00ffff\">CHIRIGOTA<\/span>!<\/strong><\/p>\n<p>Una vez finalizada la actuaci\u00f3n, tuvo lugar el momento de \u00abrepresentaciones\u00bb. \u00a1Enhorabuena a todos!<\/p>\n<p>Por la tarde, aprovechamos para retocar los disfraces y ver un\u00a0 poquito de cine, para calmar los nervios previos a la actuaci\u00f3n. Salimos a cantar nuestra chirigota \u00a1qu\u00e9 bien nos ha salido!<\/p>\n<p>&nbsp;<\/p>\n<p>Esperamos que os hayan gustado (las de alumnado, familias y equipo) y se lo traslad\u00e9is\u00a0 a vuestros hijos, la prepararon con mucho inter\u00e9s e ilusi\u00f3n.<\/p>\n<p>Fue un placer compartir con vosotros la\u00a0merienda, tuvimos el gusto de charlar un ratito con muchos de vosotros, y con los que no, esperamos que pasarais un buen rato. \u00a0Agradecemos desde aqu\u00ed la colaboraci\u00f3n de las familias en la organizaci\u00f3n y recogida.<\/p>\n<p>Juanjo y Laura<\/p>\n<p>Tutores segundo ciclo<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1\u00a1\u00a1Lleg\u00f3 el momento de nuestra gran fiesta de carnaval!!! Desde primera hora disfrutamos de los disfraces del alumnado,\u00a0 el cole est\u00e1 invadido de color, buen humor y muchos y variados personajes de todos los estilos. A primera hora aprovechamos para juntarnos los grupos de 3\u00ba y 4\u00ba y compartir nuestros disfraces, nos presentamos y hacemos &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2024\/02\/27\/carnaval-carnaval-5\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">CARNAVAL, CARNAVAL&#8230;<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,6,59,60],"tags":[552],"class_list":["post-30147","post","type-post","status-publish","format-standard","hentry","category-3o-epo","category-4o-epo","category-semanario-3o","category-semanario-4o","tag-carnaval-2024"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4lw4c-7Qf","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/comments?post=30147"}],"version-history":[{"count":4,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30147\/revisions"}],"predecessor-version":[{"id":30195,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30147\/revisions\/30195"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/media?parent=30147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/categories?post=30147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/tags?post=30147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}