{"id":30386,"date":"2024-04-07T11:10:44","date_gmt":"2024-04-07T09:10:44","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/?p=30386"},"modified":"2024-04-07T11:11:44","modified_gmt":"2024-04-07T09:11:44","slug":"30386","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2024\/04\/07\/30386\/","title":{"rendered":"Comienza la recta final en 4\u00ba"},"content":{"rendered":"<p>Estimadas familias,<\/p>\n<p><strong><em>El tiempo pasa volando, hace \u00abunas semanas\u00bb nos ve\u00edamos para empezar un nuevo curso cargado de ilusi\u00f3n \u00a0y con muchas expectativas, pero tambi\u00e9n con incertidumbre y dudas. Y sin darnos cuenta, acaba la primera semana de la recta final de este curso \u00a1TERCER TRIMESTRE!<\/em><\/strong><\/p>\n<p>Hab\u00eda muchas ganas de reencuentro, de hablar, de jugar, de contar c\u00f3mo nos ha ido en estos d\u00edas. Me alegro que hay\u00e1is disfrutado de distintos planes y actividades que han servido para recargar \u00ablas pilas\u00bb.<\/p>\n<p><em>El jard\u00edn nos recibe de forma majestuosa, los \u00e1rboles, los arbustos y los bulbos han florecido y ALQUER\u00cdA HUELE A PRIMAVERA y nosotros lo disfrutamos en cada rinc\u00f3n y paseo que hacemos por \u00e9l.<\/em><\/p>\n<p>Lo primero que hacemos para retomar la din\u00e1mica, es planificarnos, y para ello hablamos sobre las actividades, salidas, temas de trabajo que nos esperan en este tercer trimestre, y anotamos en la agenda las fechas m\u00e1s importantes que sabemos hasta ahora (pod\u00e9is consultar su agenda para m\u00e1s informaci\u00f3n).<\/p>\n<p><span style=\"color: #800080\"><strong>TRABAJO EN EQUIPO<\/strong><\/span><\/p>\n<p>En esta semana se ha ido trabajando sobre el proyecto de Andaluc\u00eda por grupos. Han terminado la b\u00fasqueda de informaci\u00f3n, se han elaborado las presentaciones en Canva para la exposici\u00f3n final y se han hecho algunos ensayos para comprobar que se tiene el contenido controlado. No todos los grupos trabajan igual, cada uno presenta sus dificultades, y en ellas trabajamos, bien sean de organizaci\u00f3n, funcionamiento, falta de planificaci\u00f3n, falta de responsabilidad o implicaci\u00f3n de alg\u00fan\/os miembros&#8230; esto es un trabajo en equipo, y eso es aprender, de las capacidades y\u00a0 limitaciones propias y de los dem\u00e1s, esto nos prepara para la vida, pues afrontar estos problemas con acompa\u00f1amiento poniendo el foco en el compa\u00f1erismo, la empat\u00eda y la asertividad, es la base para poder hacerlo de forma aut\u00f3noma y con asertividad y empat\u00eda en un futuro. Esto que les ocurre aqu\u00ed, ahora a estos niveles m\u00e1s inferiores es \u00a1como la vida misma! as\u00ed que mejor que evitarlos, afrontarlos y resolverlos.<\/p>\n<p>La pr\u00f3xima semana ser\u00e1n las exposiciones de los grupos y posteriormente se trabajar\u00e1 sobre los contenidos expuestos para que todo el grupo los asiente.<\/p>\n<p><span style=\"color: #000080\"><strong>FRACCIONES<\/strong><\/span><\/p>\n<p>Retomamos el tema de las fracciones,\u00a0 haciendo un peque\u00f1o repaso de lo trabajado, como: lectura, escritura y representaci\u00f3n de fracciones.<\/p>\n<p>Introducimos conceptos nuevos como:<\/p>\n<ul>\n<li>fracciones equivalentes,<\/li>\n<li>suma y resta de fracciones,<\/li>\n<li>hallar la fracci\u00f3n de una cantidad<\/li>\n<li>y, como profundizaci\u00f3n en los pr\u00f3ximos d\u00edas se ver\u00e1n las fracciones impropias o n\u00fameros mixtos.<\/li>\n<\/ul>\n<p><span style=\"color: #000080\"><strong>RESOLUCI\u00d3N DE PROBLEMAS<\/strong><\/span><\/p>\n<p>Continuamos analizando enunciados. El lenguaje y la redacci\u00f3n se hace de manera distinta para seguir analizando y comprendiendo mejor.\u00a0<em>La lectura comprensiva es imprescindible, as\u00ed como detectar la operaci\u00f3n necesaria para la resoluci\u00f3n y, por \u00faltimo, resolver la\/s operaci\u00f3n <\/em><i>adecuadamente.<\/i><\/p>\n<p>Se inicia un nuevo cuaderno de ocho y medio, cada cual adecuado a su ritmo y nivel.<\/p>\n<p><strong><span style=\"color: #ff6600\">LOS DOCE TRABAJOS DE HERACLES<\/span><\/strong><\/p>\n<p>Continuamos con la fascinante historia mitol\u00f3gica de \u00abLos doce trabajos de Heracles\u00bb.<\/p>\n<p>Esta semana ha tenido lugar el sexto de los trabajos, \u00abLas aves del Est\u00ednfalo\u00bb.\u00a0 La narraci\u00f3n de la historia de manera escrita est\u00e1 teniendo en todos un avance espectacular, el uso de vocabulario nuevo, expresiones que enriquecen el texto, estructura y organizaci\u00f3n de ideas cada vez m\u00e1s claras, as\u00ed como la continua mejora de la ortograf\u00eda son aspectos notorios en sus trabajos escritos. En algunos casos hay que seguir haciendo incidencia en la graf\u00eda, para seguir ganando en calidad de forma.<\/p>\n<p>Puesto que cada cual tiene un ritmo de trabajo distinto, unido a las ausencias, nos encontramos ante una situaci\u00f3n muy heterog\u00e9nea en cuanto a entrega de trabajos. Por ello, y para trabajar la autonom\u00eda, se ha dispuesto un cartel en clase con el listado del alumnado y todos los trabajos hasta la fecha, de modo que son ellos mismo los encargados de ir completando su registro con lo ya terminado, as\u00ed pueden ir controlando, planificando y gestionando ellos mismos lo que tienen pendiente. Os animo a que ve\u00e1is con ellos los trabajos del tabl\u00f3n, y a que les anim\u00e9is a ellos a ir cumpliendo con el trabajo atrasado, si se acumulan muchos al final es muy costoso terminarlo y no me gustar\u00eda que alguien se quedara sin poder hacer su libro.<\/p>\n<p><strong><span style=\"color: #ff6600\">COMPRENSI\u00d3N LECTORA<\/span><\/strong><\/p>\n<p>Hemos hecho una actividad individual donde la comprensi\u00f3n lectora del texto se hace imprescindible para poder realizar las actividades posteriores. La premisa es hacerla solos, sin ayuda ni preguntas, leyendo y releyendo el texto para ser capaces de contestar las preguntas a continuaci\u00f3n.<\/p>\n<p>Con esta actividad se trabaja tanto la <span style=\"color: #ff6600\"><em>comprensi\u00f3n\u00a0 literal<\/em><\/span> (informaci\u00f3n que aparece con datos en el texto) como la <em><span style=\"color: #ff6600\">comprensi\u00f3n\u00a0inferencial <\/span><\/em>(aquella que se deduce, est\u00e1 impl\u00edcita en el texto). Adem\u00e1s con esta misma lectura se han hecho otras de contenido gramatical y otras de expresi\u00f3n escrita.<\/p>\n<p>Visitamos la biblioteca para disfrutar de un buen rato de lectura en uno de los lugares m\u00e1s id\u00f3neos para ello, la biblioteca del cole. Se da tambi\u00e9n intercambio de libros, prestamos y devoluciones, y en algunos casos se disfruta de una tertulia en peque\u00f1o grupo sobre un libro en concreto.<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2024\\\/04\\\/07\\\/30386\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30418\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/27ded3e2-5d10-441c-a878-4d1013e72a67.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"27ded3e2-5d10-441c-a878-4d1013e72a67\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/27ded3e2-5d10-441c-a878-4d1013e72a67-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/27ded3e2-5d10-441c-a878-4d1013e72a67-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/27ded3e2-5d10-441c-a878-4d1013e72a67.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"27ded3e2-5d10-441c-a878-4d1013e72a67\" alt=\"27ded3e2-5d10-441c-a878-4d1013e72a67\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30420\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/3c84709c-05b1-4596-9d99-9cd18f2525f0.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3c84709c-05b1-4596-9d99-9cd18f2525f0\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/3c84709c-05b1-4596-9d99-9cd18f2525f0-225x300.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/3c84709c-05b1-4596-9d99-9cd18f2525f0-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/3c84709c-05b1-4596-9d99-9cd18f2525f0.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"3c84709c-05b1-4596-9d99-9cd18f2525f0\" alt=\"3c84709c-05b1-4596-9d99-9cd18f2525f0\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30421\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae-225x300.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae\" alt=\"c773fc3b-6ee7-44e6-90d7-381f9d9ca9ae\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30422\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/38fa88cd-c008-48db-919f-8f4f658eb3ee.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"38fa88cd-c008-48db-919f-8f4f658eb3ee\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/38fa88cd-c008-48db-919f-8f4f658eb3ee-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/38fa88cd-c008-48db-919f-8f4f658eb3ee-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/38fa88cd-c008-48db-919f-8f4f658eb3ee.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"38fa88cd-c008-48db-919f-8f4f658eb3ee\" alt=\"38fa88cd-c008-48db-919f-8f4f658eb3ee\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<p><span style=\"color: #ff00ff\"><strong>JUEGOS DE MESA<\/strong><\/span><\/p>\n<p>Como sab\u00e9is, los viernes dedicamos una sesi\u00f3n a juegos de mesa, en algunas ocasiones son elegidos por m\u00ed para trabajar objetivos concretos y otras son ellos mismos los que deciden a qu\u00e9 quieren jugar. Os dejo algunas im\u00e1genes de esta sesi\u00f3n.<\/p>\n<div class=\"tiled-gallery type-square tiled-gallery-unresized\" data-original-width=\"474\" data-carousel-extra='{&quot;blog_id&quot;:7,&quot;permalink&quot;:&quot;https:\\\/\\\/www.alqueria.es\\\/blogs\\\/alqueriasegundociclo\\\/2024\\\/04\\\/07\\\/30386\\\/&quot;,&quot;likes_blog_id&quot;:64233500}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30426\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/05e5507d-37e1-4f39-a274-2b65464d5a63.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"05e5507d-37e1-4f39-a274-2b65464d5a63\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/05e5507d-37e1-4f39-a274-2b65464d5a63-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/05e5507d-37e1-4f39-a274-2b65464d5a63-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/05e5507d-37e1-4f39-a274-2b65464d5a63.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"05e5507d-37e1-4f39-a274-2b65464d5a63\" alt=\"05e5507d-37e1-4f39-a274-2b65464d5a63\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30425\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/30f2ee3f-f3cf-4372-b03e-4ae750b229b5.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"30f2ee3f-f3cf-4372-b03e-4ae750b229b5\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/30f2ee3f-f3cf-4372-b03e-4ae750b229b5-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/30f2ee3f-f3cf-4372-b03e-4ae750b229b5-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/30f2ee3f-f3cf-4372-b03e-4ae750b229b5.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"30f2ee3f-f3cf-4372-b03e-4ae750b229b5\" alt=\"30f2ee3f-f3cf-4372-b03e-4ae750b229b5\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <div class=\"gallery-row\" style=\"width: 474px; height: 237px;\" data-original-width=\"474\" data-original-height=\"237\" > <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30424\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/006ff016-5676-4f1b-91b1-c4e7bfad9312.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"006ff016-5676-4f1b-91b1-c4e7bfad9312\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/006ff016-5676-4f1b-91b1-c4e7bfad9312-225x300.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/006ff016-5676-4f1b-91b1-c4e7bfad9312-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/006ff016-5676-4f1b-91b1-c4e7bfad9312.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"006ff016-5676-4f1b-91b1-c4e7bfad9312\" alt=\"006ff016-5676-4f1b-91b1-c4e7bfad9312\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <div class=\"gallery-group\" style=\"width: 237px; height: 237px;\" data-original-width=\"237\" data-original-height=\"237\" > <div class=\"tiled-gallery-item \" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"233\"> <meta itemprop=\"height\" content=\"233\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"30423\" data-orig-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/ae1c90bb-f953-427c-890e-d2c70b55c76d.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ae1c90bb-f953-427c-890e-d2c70b55c76d\" data-image-description=\"\" data-medium-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/ae1c90bb-f953-427c-890e-d2c70b55c76d-300x225.jpg\" data-large-file=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/ae1c90bb-f953-427c-890e-d2c70b55c76d-1024x768.jpg\" src=\"https:\/\/i0.wp.com\/cloud.alqueria.es\/wp-content\/uploads\/sites\/7\/2024\/04\/ae1c90bb-f953-427c-890e-d2c70b55c76d.jpg?w=233&#038;h=233&#038;crop=1&#038;ssl=1\" width=\"233\" height=\"233\" loading=\"lazy\" data-original-width=\"233\" data-original-height=\"233\" itemprop=\"http:\/\/schema.org\/image\" title=\"ae1c90bb-f953-427c-890e-d2c70b55c76d\" alt=\"ae1c90bb-f953-427c-890e-d2c70b55c76d\" style=\"width: 233px; height: 233px;\" \/> <\/div> <\/div> <\/div> <\/div>\n<p><span style=\"color: #008000\"><strong>PATRULLA MEDIOAMBIENTAL<\/strong><\/span><\/p>\n<p>Retomamos la actividad de la Patrulla Medioambiental, en la que varios compa\u00f1eros\/as de cada clase de primaria (turnos rotatorios) se agrupan para desempe\u00f1ar diferentes tareas: comprobar que los grifos est\u00e9n cerrados, luces y PDIs apagadas, clases ventiladas, ropa colocada en los percheros, recogida de papeles y reciclado de los contenedores azul y amarillo, huerto y alimentaci\u00f3n de animales\u2026<\/p>\n<p>Una actividad de concienciaci\u00f3n medioambiental, empezando por lo m\u00e1s cercano, el espacio donde aprendo y disfruto, mi cole.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/5\/2024\/04\/abril-2.jpeg\" \/><\/p>\n<p><em><strong>Por si no veis la agenda, el pr\u00f3ximo viernes 12 tendremos nuestra salida cultural al Centro Jos\u00e9 Guerrero, donde visitaremos la exposici\u00f3n temporal de Miquel Mont titulada \u00abProgreso contra progreso\u00bb.\u00a0<\/strong><\/em><\/p>\n<p>Laura Justicia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias, El tiempo pasa volando, hace \u00abunas semanas\u00bb nos ve\u00edamos para empezar un nuevo curso cargado de ilusi\u00f3n \u00a0y con muchas expectativas, pero tambi\u00e9n con incertidumbre y dudas. Y sin darnos cuenta, acaba la primera semana de la recta final de este curso \u00a1TERCER TRIMESTRE! Hab\u00eda muchas ganas de reencuentro, de hablar, de jugar, &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2024\/04\/07\/30386\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Comienza la recta final en 4\u00ba<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,60],"tags":[],"class_list":["post-30386","post","type-post","status-publish","format-standard","hentry","category-4o-epo","category-semanario-4o"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s4lw4c-30386","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/comments?post=30386"}],"version-history":[{"count":2,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30386\/revisions"}],"predecessor-version":[{"id":30428,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/30386\/revisions\/30428"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/media?parent=30386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/categories?post=30386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/tags?post=30386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}