{"id":31971,"date":"2025-02-09T23:12:54","date_gmt":"2025-02-09T22:12:54","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/?p=31971"},"modified":"2025-02-09T23:13:51","modified_gmt":"2025-02-09T22:13:51","slug":"31971","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2025\/02\/09\/31971\/","title":{"rendered":"EL CINE"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">La pr\u00f3xima semana celebraremos nuestra esperada Semana Cultural, y este a\u00f1o el protagonista es<strong> EL CINE.<\/strong><\/p>\n<p data-pm-slice=\"1 1 []\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/img.freepik.com\/vector-premium\/doodle-conjunto-iconos-simples-cine_8043-398.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Doodle conjunto de iconos simples de cine\" width=\"330\" height=\"410\" \/><\/p>\n<p data-pm-slice=\"1 1 []\">Durante las \u00faltimas semanas, hemos estado trabajando intensamente en torno a nuestras pel\u00edculas favoritas, explorando distintos aspectos del s\u00e9ptimo arte y desarrollando nuestra creatividad.<\/p>\n<p>Cada uno\/a ha elegido su pel\u00edcula preferida y ha elaborado su propio <strong>tr\u00e1iler,<\/strong> algunos han coincidido en gustos, es por ello que ha habido trabajos individuales, en parejas, tr\u00edos o grupos m\u00e1s numerosos.<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/img.freepik.com\/foto-gratis\/es-letra-pelicula-encima-camara-cine-vintage_23-2148416753.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Es la letra de la pel\u00edcula encima de la c\u00e1mara de cine vintage\" width=\"444\" height=\"444\" \/><\/p>\n<p>Para ello, primero han tenido que crear un <strong>storyboard<\/strong>, una herramienta esencial en el mundo audiovisual que permite planificar escena por escena, organizando visualmente la historia antes de grabar. Este proceso ha supuesto poner en pr\u00e1ctica varias funciones ejecutivas simult\u00e1neamente: planificaci\u00f3n, organizaci\u00f3n, toma de decisiones y creatividad.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/img.freepik.com\/vector-gratis\/ilustracion-proceso-guion-grafico_23-2148679315.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Ilustraci\u00f3n del proceso del gui\u00f3n gr\u00e1fico\" width=\"405\" height=\"270\" \/><\/p>\n<p>El montaje del tr\u00e1iler se ha llevado a cabo con <strong>Canva<\/strong>, una plataforma que ofrece innumerables posibilidades para la edici\u00f3n de video. Han aprendido a utilizar im\u00e1genes de libre uso, a realizar animaciones, a escribir textos con distintas tipograf\u00edas y a sincronizar efectos con precisi\u00f3n. Adem\u00e1s, han incorporado m\u00fasica y trabajado con diversos materiales:<strong> algunos proporcionados por el propio programa, otros generados con la IA de Canva, y hasta han utilizado figuras como mu\u00f1ecos tipo Lego o Playmobil, as\u00ed como sus propias ilustraciones.<\/strong> Ha sido un trabajo de gran valor y esfuerzo.<\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/img.freepik.com\/fotos-premium\/playmobil-fondo-blanco-alta-calidad-ultra_889056-8400.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Playmobil con fondo blanco alta calidad ultra\" width=\"252\" height=\"252\" \/><img decoding=\"async\" class=\"\" src=\"https:\/\/img.freepik.com\/fotos-premium\/monton-legos-que-estan-mesa_1085731-707.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"un mont\u00f3n de legos que est\u00e1n en una mesa\" width=\"192\" height=\"343\" \/><\/p>\n<p>Durante la Semana Cultural, los tr\u00e1ilers ser\u00e1n proyectados y publicados en este blog, para que todos pod\u00e1is disfrutar de tanto talento \u00a1lo que se ha perdido la academia de cine!<\/p>\n<p>Pero hay m\u00e1s sorpresas: una de las actividades m\u00e1s especiales ha sido la creaci\u00f3n del <strong>cartel de su pel\u00edcula favorita<\/strong>. Hasta ahora, solo han visto la foto que les hemos hecho, pero el montaje final (que nosotros ya hemos visto) promete ser impresionante.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/img.freepik.com\/foto-gratis\/arreglo-pelicula-letras-cine_23-2148425087.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Arreglo de pel\u00edcula con letras de cine\" width=\"401\" height=\"267\" \/><\/p>\n<p>Mientras tanto, seguimos avanzando en otros proyectos. Continuamos nuestra aventura con <strong>\u00abLa Odisea\u00bb<\/strong>, viviendo junto a Odiseo su regreso a casa y todas las haza\u00f1as que le ocurren. Tambi\u00e9n hemos trabajado en el <strong>c\u00e1lculo y la resoluci\u00f3n de problemas<\/strong> con el <strong>cuaderno de ocho y medio<\/strong>, y hemos realizado actividades de repaso sobre <strong>el cuerpo humano<\/strong>, incluyendo la prueba <strong>\u00abQu\u00e9 he aprendido\u00bb<\/strong>, para evaluar de manera personal nuestros conocimientos.<\/p>\n<p>Por otro lado, estamos completamente inmersos en la creaci\u00f3n de nuestra <strong>chirigota<\/strong>. Ya tenemos la canci\u00f3n que servir\u00e1 de base y casi la letra terminada, son mayores y se va notando&#8230; el resultado est\u00e1 siendo sorprendente.<\/p>\n<p>Quiero aprovechar para animar a todas las familias a sumarse al grupo de chirigota de familias, es una ocasi\u00f3n especial para compartir, re\u00edr y disfrutar juntos del esp\u00edritu del carnaval. Os invitamos a colaborar en los ensayos, en la preparaci\u00f3n de los disfraces y, por supuesto, a disfrutar de una tarde maravillosa!<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/img.freepik.com\/fotos-premium\/payaso-nino-divertido-poppers-fiesta-nino-feliz-jugando-casa-concepto-dia-inocentes-1-abril_411285-683.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Payaso ni\u00f1o divertido con poppers de fiesta. Ni\u00f1o feliz jugando en casa. Concepto del d\u00eda de los inocentes del 1 de abril\" width=\"341\" height=\"512\" \/><\/p>\n<p>Finalmente, pero no menos importante, os comento que seguimos adelante con nuestro <strong>proyecto de emprendimiento<\/strong>, siguiendo todas las fases: creaci\u00f3n de la idea, an\u00e1lisis, estrategias de marketing,\u00a0 y mucho m\u00e1s. Una vez finalizada la Semana Cultural, nos sumergiremos de lleno en este trabajo pues el tiempo apremia. Lo m\u00e1s emocionante es que la sensaci\u00f3n de equipo es m\u00e1s fuerte cada sesi\u00f3n, tenemos m\u00e1s claro que\u00a0 <strong>esto es de todos y todos aportamos<\/strong>. \u00a1Objetivo conseguido!<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/img.freepik.com\/fotos-premium\/poner-marcha-concepto-idea-vector_13339-296537.jpg?ga=GA1.1.1496029621.1737571745&amp;semt=ais_incoming\" alt=\"Poner en marcha el concepto de idea vector\" width=\"381\" height=\"456\" \/><\/p>\n<p>Os animamos a que nos sig\u00e1is por este medio, donde compartiremos todo lo que ocurra en esta <strong>Semana de Cine.<\/strong><\/p>\n<p>Laura Justicia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pr\u00f3xima semana celebraremos nuestra esperada Semana Cultural, y este a\u00f1o el protagonista es EL CINE. Durante las \u00faltimas semanas, hemos estado trabajando intensamente en torno a nuestras pel\u00edculas favoritas, explorando distintos aspectos del s\u00e9ptimo arte y desarrollando nuestra creatividad. Cada uno\/a ha elegido su pel\u00edcula preferida y ha elaborado su propio tr\u00e1iler, algunos han &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/2025\/02\/09\/31971\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">EL CINE<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,60],"tags":[385,578,579,577,576],"class_list":["post-31971","post","type-post","status-publish","format-standard","hentry","category-4o-epo","category-semanario-4o","tag-cine","tag-pelicula-favorita","tag-semana-cultural-cine","tag-story-board","tag-trailer"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s4lw4c-31971","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/31971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/comments?post=31971"}],"version-history":[{"count":2,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/31971\/revisions"}],"predecessor-version":[{"id":31973,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/posts\/31971\/revisions\/31973"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/media?parent=31971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/categories?post=31971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriasegundociclo\/wp-json\/wp\/v2\/tags?post=31971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}