{"id":9672,"date":"2014-09-12T13:28:56","date_gmt":"2014-09-12T11:28:56","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/?p=9672"},"modified":"2014-10-23T23:08:37","modified_gmt":"2014-10-23T21:08:37","slug":"nuevo-curso-nueva-vida-en-5o-epo","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/2014\/09\/12\/nuevo-curso-nueva-vida-en-5o-epo\/","title":{"rendered":"Nuevo curso, nueva vida en 5\u00ba EPO"},"content":{"rendered":"<h5><img decoding=\"async\" data-attachment-id=\"9675\" data-permalink=\"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/2014\/09\/12\/nuevo-curso-nueva-vida-en-5o-epo\/dsc09196\/#main\" data-orig-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-content\/uploads\/sites\/13\/2014\/09\/DSC09196.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"grupo de 5\u00ba\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-content\/uploads\/sites\/13\/2014\/09\/DSC09196.jpg\" class=\"aligncenter size-medium wp-image-9675\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/13\/2014\/09\/DSC09196-300x225.jpg\" alt=\"grupo de 5\u00ba\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-content\/uploads\/sites\/13\/2014\/09\/DSC09196-300x225.jpg 300w, https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-content\/uploads\/sites\/13\/2014\/09\/DSC09196.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Este curso tenemos muchas cosas que hacer, Jorge nos lo ha explicado todo con mucha paciencia.<\/h5>\n<h5>Todo el mundo est\u00e1 de acuerdo con que Jorge sea nuestro profe. Ya queremos saber en qu\u00e9 nos sorprender\u00e1 este curso. Mates, lengua y cono \u00a1\u00bfqu\u00e9 ser\u00e1 lo m\u00e1s dif\u00edcil?!<\/h5>\n<h5>Quien sabe, igual nos suspende a todos&#8230;<\/h5>\n<h5>Este a\u00f1o vamos a tener nuevas tecnolog\u00edas en 2.0: Tablets, edmodo, PowToon, el nuevo blog&#8230; \u00a1Hay muchas cosas por hacer!<\/h5>\n<h5>Esperamos muchas cosas de 5\u00ba como por ejemplo: sacar buenas notas, pas\u00e1rnoslo muy bien, pero desgraciadamente, hay que estudiar.<\/h5>\n<h5>Lo que todos esperamos de 5\u00ba es que sea un a\u00f1o divertido y lleno de sorpresas.<\/h5>\n<h5>Todos estamos muy emocionados con las cosas que vamos a descubrir, ense\u00f1ar, aprender, estudiar y sobre todo por hacer.<\/h5>\n<h5><span style=\"color: #ff0000\">Marina, Elena de la Ch, Carmen y Lara<\/span><\/h5>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este curso tenemos muchas cosas que hacer, Jorge nos lo ha explicado todo con mucha paciencia. Todo el mundo est\u00e1 de acuerdo con que Jorge sea nuestro profe. Ya queremos saber en qu\u00e9 nos sorprender\u00e1 este curso. Mates, lengua y cono \u00a1\u00bfqu\u00e9 ser\u00e1 lo m\u00e1s dif\u00edcil?! Quien sabe, igual nos suspende a todos&#8230; Este a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,5],"tags":[260,259],"class_list":["post-9672","post","type-post","status-publish","format-standard","hentry","category-5o-epo","category-alumnos-6o-epo","tag-bienvenida","tag-inicio-curso"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4mLU4-2w0","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/posts\/9672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/comments?post=9672"}],"version-history":[{"count":0,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/posts\/9672\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/media?parent=9672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/categories?post=9672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriatercerciclo\/wp-json\/wp\/v2\/tags?post=9672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}