{"id":28046,"date":"2022-10-06T17:29:53","date_gmt":"2022-10-06T15:29:53","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/?p=28046"},"modified":"2022-10-06T17:29:53","modified_gmt":"2022-10-06T15:29:53","slug":"juego-heuristico-156","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/2022\/10\/06\/juego-heuristico-156\/","title":{"rendered":"JUEGO HEUR\u00cdSTICO"},"content":{"rendered":"\r\n<p>Llegamos a jueves y vamos avanzando muy deprisa en nuestra adaptaci\u00f3n a la vida en la escuela.<\/p>\r\n<p>Hoy comenzamos, como siempre, con un rato de juego en la Clase Amarilla tras lo que toca volver a nuestra aula y ponernos a trabajar&#8230;\u00a1 Qu\u00e9 trabajadores los \u00abazulitos\u00bb!.<\/p>\r\n<p>Tras el primer control de esf\u00ednteres sacamos los materiales y nos ponemos a investigar en una nueva sesi\u00f3n de Juego Heur\u00edstico. Gomas, tapaderas, conos y latas contenedoras dan para muchos minutos de juego&#8230;y sobre todo de recoger y clasificar.<\/p>\r\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-28046-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0007-300x225.jpg&quot;,&quot;id&quot;:&quot;28072&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0007&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0006-300x225.jpg&quot;,&quot;id&quot;:&quot;28071&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0006&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0009-300x225.jpg&quot;,&quot;id&quot;:&quot;28070&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0009&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0005-300x225.jpg&quot;,&quot;id&quot;:&quot;28067&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0005&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\r\n<p>M\u00fasica de baile antes de sentarnos en asamblea a comer un poco de fruta fresquita,,,\u00a1 Con este calor apetece bastante!. Comemos pl\u00e1tano, pera y mel\u00f3n.<\/p>\r\n<p>Continuamos con un buen rato de juego en la terraza con las motos, las bicis, correpasillos, pelotas&#8230;\u00a1 Y alguno se duerme en una cortita siesta ma\u00f1anera !<\/p>\r\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-28046-2-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0008-300x225.jpg&quot;,&quot;id&quot;:&quot;28069&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0008&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221006-WA0003-300x225.jpg&quot;,&quot;id&quot;:&quot;28068&quot;,&quot;title&quot;:&quot;IMG-20221006-WA0003&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\r\n<p>Volvemos a la clase y jugamos con los animales mientras vamos pasando por un nuevo control de esf\u00ednteres que termina con un buen lavado de cara y manos y&#8230; \u00a1A COMEERRRR!<\/p>\r\n<p>Una ma\u00f1ana estupenda.<\/p>\r\n<p>Un abrazo<\/p>\r\n<p>Nuria<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Llegamos a jueves y vamos avanzando muy deprisa en nuestra adaptaci\u00f3n a la vida en la escuela. Hoy comenzamos, como siempre, con un rato de juego en la Clase Amarilla tras lo que toca volver a nuestra aula y ponernos a trabajar&#8230;\u00a1 Qu\u00e9 trabajadores los \u00abazulitos\u00bb!. Tras el primer control de esf\u00ednteres sacamos los materiales &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/2022\/10\/06\/juego-heuristico-156\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">JUEGO HEUR\u00cdSTICO<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,8],"tags":[],"class_list":["post-28046","post","type-post","status-publish","format-standard","hentry","category-clase-azul","category-juego-heuristico"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4mlAA-7im","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/comments?post=28046"}],"version-history":[{"count":7,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28046\/revisions"}],"predecessor-version":[{"id":28078,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28046\/revisions\/28078"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/media?parent=28046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/categories?post=28046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/tags?post=28046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}