{"id":28195,"date":"2022-10-18T17:54:57","date_gmt":"2022-10-18T15:54:57","guid":{"rendered":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/?p=28195"},"modified":"2022-10-18T16:00:08","modified_gmt":"2022-10-18T14:00:08","slug":"taller-de-artistica-estampacion-2","status":"publish","type":"post","link":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/2022\/10\/18\/taller-de-artistica-estampacion-2\/","title":{"rendered":"TALLER DE ART\u00cdSTICA. Estampaci\u00f3n"},"content":{"rendered":"\r\n<p>Hoy, como cada d\u00eda, comenzamos la jornada con un rato de juego en la clase amarilla para luego ir a nuestra clase para comenzar las actividades programadas de la\u00a0 ma\u00f1ana.<\/p>\r\n<p>La actividad m\u00e1s interesante de la ma\u00f1ana es nuestro Taller de Art\u00edstica en donde hoy practicamos con la t\u00e9cnica de estampaci\u00f3n con unos tampones de hojas que pintamos con los colores de oto\u00f1o : rojo, marr\u00f3n, amarillo, verde&#8230;<\/p>\r\n<p>La fase de la estampaci\u00f3n es dirigida y breve por lo que continuamos estampando y pintando libremente sobre un folio&#8230;\u00a1 Nos encanta!. y ya adem\u00e1s de tampones utilizamos los dedos, la mano&#8230;<\/p>\r\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-28195-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0007-225x300.jpg&quot;,&quot;id&quot;:&quot;28221&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0007&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0002-300x225.jpg&quot;,&quot;id&quot;:&quot;28220&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0002&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0003-225x300.jpg&quot;,&quot;id&quot;:&quot;28219&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0003&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0004-225x300.jpg&quot;,&quot;id&quot;:&quot;28218&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0004&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0005-300x225.jpg&quot;,&quot;id&quot;:&quot;28217&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0005&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/cloud.alqueria.es\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2022\\\/10\\\/IMG-20221018-WA0010-225x300.jpg&quot;,&quot;id&quot;:&quot;28215&quot;,&quot;title&quot;:&quot;IMG-20221018-WA0010&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\r\n<p>Llega Lola con su ingl\u00e9s y nos ayuda en la tarea del taller y para terminar con el lavado de manos.\u00a0<\/p>\r\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-28224\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008-300x225.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008-1024x768.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008-768x576.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008-1536x1152.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0008.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Todo limpio y recogido antes de seguir con la asamblea de la fruta en donde comemos unos ricos pl\u00e1tanos y unas deliciosas mandarinas.<\/p>\r\n<p>Nos preparamos para salir al parque a disfrutar de este d\u00eda de calor en el que parece volvemos al verano.<\/p>\r\n<p><img decoding=\"async\" class=\"alignleft size-medium wp-image-28214\" src=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000-300x225.jpg 300w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000-1024x768.jpg 1024w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000-768x576.jpg 768w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000-1536x1152.jpg 1536w, https:\/\/cloud.alqueria.es\/wp-content\/uploads\/sites\/10\/2022\/10\/IMG-20221018-WA0000.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Jugamos en el arenero, el c\u00e9sped, la casita&#8230;\u00a1 Estupendo!<\/p>\r\n<p>Tras la siesta nos sentamos en un mini taller con los puzles\u00a0 en compa\u00f1\u00eda de los compa\u00f1eros de la clase amarilla.<\/p>\r\n<p>Una jornada muy interesante.<\/p>\r\n<p>Un abrazo<\/p>\r\n<p>Nuria.<\/p>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Hoy, como cada d\u00eda, comenzamos la jornada con un rato de juego en la clase amarilla para luego ir a nuestra clase para comenzar las actividades programadas de la\u00a0 ma\u00f1ana. La actividad m\u00e1s interesante de la ma\u00f1ana es nuestro Taller de Art\u00edstica en donde hoy practicamos con la t\u00e9cnica de estampaci\u00f3n con unos tampones de &hellip; <a href=\"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/2022\/10\/18\/taller-de-artistica-estampacion-2\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">TALLER DE ART\u00cdSTICA. Estampaci\u00f3n<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[162,5],"tags":[],"class_list":["post-28195","post","type-post","status-publish","format-standard","hentry","category-artistica","category-clase-azul"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4mlAA-7kL","_links":{"self":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/comments?post=28195"}],"version-history":[{"count":6,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28195\/revisions"}],"predecessor-version":[{"id":28228,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/posts\/28195\/revisions\/28228"}],"wp:attachment":[{"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/media?parent=28195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/categories?post=28195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alqueria.es\/blogs\/alqueriazulceleste\/wp-json\/wp\/v2\/tags?post=28195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}